{"id":88032,"date":"2021-06-14T16:04:53","date_gmt":"2021-06-14T19:04:53","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=88032"},"modified":"2021-06-14T17:34:04","modified_gmt":"2021-06-14T20:34:04","slug":"melhorias-nos-cemiterios-de-muriae-e-sao-fernando","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/melhorias-nos-cemiterios-de-muriae-e-sao-fernando\/","title":{"rendered":"Melhorias nos cemit\u00e9rios de Muria\u00e9 e S\u00e3o Fernando"},"content":{"rendered":"\n<h5 class=\"wp-block-heading\"><em>M\u00e1quinas tiraram troncos e nivelaram o caminho de acesso ao campo santo de S\u00e3o Fernando<\/em><\/h5>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2021\/06\/cemiterio-sao-fernando.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"430\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2021\/06\/cemiterio-sao-fernando.jpg\" alt=\"\" class=\"wp-image-88034\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2021\/06\/cemiterio-sao-fernando.jpg 800w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2021\/06\/cemiterio-sao-fernando-300x161.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2021\/06\/cemiterio-sao-fernando-768x413.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A Prefeitura de Muria\u00e9 est\u00e1 envolvida em fazer restaura\u00e7\u00f5es e retirar entulhos nas partes internas e entorno dos cemit\u00e9rios da cidade, distritos e comunidades. As m\u00e1quinas tiraram troncos que dificultavam a passagem e nivelaram o caminho de acesso ao campo santo de S\u00e3o Fernando. Na cidade, em frente o Cemit\u00e9rio Senhor do Bonfim, foi realizado um recapeamento no piso, para melhorar o tr\u00e2nsito.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Em uma parceria estabelecida entre a Secretaria de Administra\u00e7\u00e3o e Agricultura, os servidores municipais recuperaram espa\u00e7os. \u201cAqui em Muria\u00e9, n\u00f3s retiramos um tronco grande de \u00e1rvore que estava jogado \u00e0 frente do port\u00e3o principal do cemit\u00e9rio. Isto causava transtornos para pedestres e motoristas e aproveitamos para melhorar o cal\u00e7amento\u201d, disse o coordenador do setor, Elias Santos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No distrito de S\u00e3o Fernando tamb\u00e9m foram realizadas algumas melhorias para facilitar o acesso da popula\u00e7\u00e3o ao local p\u00fablico. Anteriormente estava imposs\u00edvel chegar a porta do cemit\u00e9rio com ve\u00edculos para realizar o sepultamento de moradores. Era preciso ir ao local andando, carregando a urna mortu\u00e1ria nas m\u00e3os, devido a estrada n\u00e3o permitir a passagem, por causa de desn\u00edveis no terreno e o vasto matagal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fonte: ASCOM PMM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1quinas tiraram troncos e nivelaram o caminho de acesso ao campo santo de S\u00e3o Fernando A Prefeitura de Muria\u00e9 est\u00e1 envolvida em fazer restaura\u00e7\u00f5es e retirar entulhos nas partes internas e entorno dos cemit\u00e9rios da cidade, distritos e comunidades. As m\u00e1quinas tiraram troncos que dificultavam a passagem e nivelaram o caminho de acesso ao campo &#8230; <a title=\"Melhorias nos cemit\u00e9rios de Muria\u00e9 e S\u00e3o Fernando\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/melhorias-nos-cemiterios-de-muriae-e-sao-fernando\/\" aria-label=\"Read more about Melhorias nos cemit\u00e9rios de Muria\u00e9 e S\u00e3o Fernando\">Ler mais<\/a><\/p>\n","protected":false},"author":11,"featured_media":88034,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,2893,1,6],"tags":[1363,3697,4365,5610,2400],"class_list":["post-88032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-muriae","category-cotidiano","category-gerais","category-regiao","tag-cemiterio","tag-cemiterio-de-muriae","tag-cemiterio-municipal","tag-cemiterio-sao-fernando","tag-melhorias"],"acf":[],"aioseo_notices":[],"views":142,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/88032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=88032"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/88032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/88034"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=88032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=88032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=88032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}