{"id":81117,"date":"2020-07-22T17:55:30","date_gmt":"2020-07-22T20:55:30","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=81117"},"modified":"2020-07-22T17:55:30","modified_gmt":"2020-07-22T20:55:30","slug":"paroquia-do-porto-divulga-programacao-da-74a-festa-em-honra-a-sao-cristovao","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/paroquia-do-porto-divulga-programacao-da-74a-festa-em-honra-a-sao-cristovao\/","title":{"rendered":"Par\u00f3quia do Porto divulga programa\u00e7\u00e3o da 74\u00aa Festa em honra a S\u00e3o Crist\u00f3v\u00e3o"},"content":{"rendered":"<p><em>Evento acontecer\u00e1 entre sexta-feira (24) e domingo (26) e ter\u00e1 entrega de pratos t\u00edpicos por delivery<\/em><\/p>\n<figure id=\"attachment_81118\" aria-describedby=\"caption-attachment-81118\" style=\"width: 590px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2020\/07\/Matriz-Nossa-Senhora-Aparecida-Festa-da-Padroeira-Iluminacao-noturna-Foto-Guia-Muriae.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-81118\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2020\/07\/Matriz-Nossa-Senhora-Aparecida-Festa-da-Padroeira-Iluminacao-noturna-Foto-Guia-Muriae.jpg\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2020\/07\/Matriz-Nossa-Senhora-Aparecida-Festa-da-Padroeira-Iluminacao-noturna-Foto-Guia-Muriae.jpg 600w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2020\/07\/Matriz-Nossa-Senhora-Aparecida-Festa-da-Padroeira-Iluminacao-noturna-Foto-Guia-Muriae-300x225.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2020\/07\/Matriz-Nossa-Senhora-Aparecida-Festa-da-Padroeira-Iluminacao-noturna-Foto-Guia-Muriae-105x80.jpg 105w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-81118\" class=\"wp-caption-text\">Foto: Guia Muria\u00e9<\/figcaption><\/figure>\n<p>A Par\u00f3quia Nossa Senhora Aparecida, do bairro do Porto, divulgou a programa\u00e7\u00e3o da 74\u00aa Festa em honra a S\u00e3o Crist\u00f3v\u00e3o. O evento, muito tradicional na cidade, ter\u00e1 novidades para este ano: buscando evitar aglomera\u00e7\u00f5es, diante da pandemia de coronav\u00edrus, os pratos tipicamente servidos na \u00e1rea de eventos da Par\u00f3quia ser\u00e3o entregues por delivery.<!--more--><\/p>\n<p>A programa\u00e7\u00e3o ter\u00e1 in\u00edcio na sexta-feira (24), com a Santa Missa \u00e0s 19h, e delivery de pela-\u00e9gua das 19h \u00e0s 20h30. No s\u00e1bado (25), os hor\u00e1rios se mant\u00eam e o prato do dia ser\u00e1 vaca atolada. O encerramento da Festa acontece no domingo (26). Haver\u00e1 missas \u00e0s 7h e \u00e0s 9h da manh\u00e3, sendo que a das 9h ser\u00e1 a tradicional &#8220;Missa dos Motoristas, Caminhoneiros e Motociclistas&#8221;. Ap\u00f3s a mesma, haver\u00e1 carreata e b\u00ean\u00e7\u00e3o das chaves e carros.<\/p>\n<p>Ainda no domingo, o delivery ser\u00e1 de feijoada, das 10h30 \u00e0s 12h. \u00c0s 18h, acontece a Cantata de Nossa Senhora Aparecida, com transmiss\u00e3o ao vivo pelas redes sociais da Par\u00f3quia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento acontecer\u00e1 entre sexta-feira (24) e domingo (26) e ter\u00e1 entrega de pratos t\u00edpicos por delivery A Par\u00f3quia Nossa Senhora Aparecida, do bairro do Porto, divulgou a programa\u00e7\u00e3o da 74\u00aa Festa em honra a S\u00e3o Crist\u00f3v\u00e3o. O evento, muito tradicional na cidade, ter\u00e1 novidades para este ano: buscando evitar aglomera\u00e7\u00f5es, diante da pandemia de coronav\u00edrus, &#8230; <a title=\"Par\u00f3quia do Porto divulga programa\u00e7\u00e3o da 74\u00aa Festa em honra a S\u00e3o Crist\u00f3v\u00e3o\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/paroquia-do-porto-divulga-programacao-da-74a-festa-em-honra-a-sao-cristovao\/\" aria-label=\"Read more about Par\u00f3quia do Porto divulga programa\u00e7\u00e3o da 74\u00aa Festa em honra a S\u00e3o Crist\u00f3v\u00e3o\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,24,1,6],"tags":[],"class_list":["post-81117","post","type-post","status-publish","format-standard","hentry","category-muriae","category-eventos","category-gerais","category-regiao"],"acf":[],"aioseo_notices":[],"views":137,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/81117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=81117"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/81117\/revisions"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=81117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=81117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=81117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}