{"id":60905,"date":"2018-08-30T23:08:37","date_gmt":"2018-08-31T02:08:37","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=60905"},"modified":"2018-08-30T23:10:46","modified_gmt":"2018-08-31T02:10:46","slug":"sob-nova-direcao-espetos-cia-atrai-clientela-no-safira","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/","title":{"rendered":"Sob nova dire\u00e7\u00e3o, Espeto\u2019s &#038; Cia atrai clientela no Safira"},"content":{"rendered":"<p>O Espeto\u2019s &amp; Cia \u2013 Bar e Lanchonete, localizado na Avenida Silv\u00e9rio Campos, n\u00famero 510, no Bairro Safira, agora est\u00e1 sob a dire\u00e7\u00e3o do empres\u00e1rio Felipe.<\/p>\n<p>O local, que oferece cerveja gelada e espetinhos variados, tamb\u00e9m realiza entrega em domic\u00edlio de segunda a sexta-feira, a partir das 16h.<\/p>\n<p><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.01.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-60907\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.01.jpeg\" alt=\"\" width=\"890\" height=\"667\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.01.jpeg 890w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.01-300x225.jpeg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.01-768x576.jpeg 768w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02.jpeg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-60908\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02.jpeg\" alt=\"\" width=\"889\" height=\"667\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02.jpeg 889w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02-300x225.jpeg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02-768x576.jpeg 768w\" sizes=\"(max-width: 889px) 100vw, 889px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02-1.jpeg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-60909\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02-1.jpeg\" alt=\"\" width=\"890\" height=\"667\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02-1.jpeg 890w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02-1-300x225.jpeg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02-1-768x576.jpeg 768w\" sizes=\"(max-width: 890px) 100vw, 890px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Espeto\u2019s &amp; Cia \u2013 Bar e Lanchonete, localizado na Avenida Silv\u00e9rio Campos, n\u00famero 510, no Bairro Safira, agora est\u00e1 sob a dire\u00e7\u00e3o do empres\u00e1rio Felipe. O local, que oferece cerveja gelada e espetinhos variados, tamb\u00e9m realiza entrega em domic\u00edlio de segunda a sexta-feira, a partir das 16h.<\/p>\n","protected":false},"author":2,"featured_media":60909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[30],"tags":[],"class_list":["post-60905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-muriae"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"O Espeto\u2019s &amp; Cia \u2013 Bar e Lanchonete, localizado na Avenida Silv\u00e9rio Campos, n\u00famero 510, no Bairro Safira, agora est\u00e1 sob a dire\u00e7\u00e3o do empres\u00e1rio Felipe. O local, que oferece cerveja gelada e espetinhos variados, tamb\u00e9m realiza entrega em domic\u00edlio de segunda a sexta-feira, a partir das 16h.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juliana Laviola\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"A Not\u00edcia Online - Noticias de Muria\u00e9 e regi\u00e3o\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sob nova dire\u00e7\u00e3o, Espeto\u2019s &amp; Cia atrai clientela no Safira - A Not\u00edcia Online\" \/>\n\t\t<meta property=\"og:description\" content=\"O Espeto\u2019s &amp; Cia \u2013 Bar e Lanchonete, localizado na Avenida Silv\u00e9rio Campos, n\u00famero 510, no Bairro Safira, agora est\u00e1 sob a dire\u00e7\u00e3o do empres\u00e1rio Felipe. O local, que oferece cerveja gelada e espetinhos variados, tamb\u00e9m realiza entrega em domic\u00edlio de segunda a sexta-feira, a partir das 16h.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&#038;_nc_cat=111&#038;ccb=1-7&#038;_nc_sid=f907e8&#038;_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&#038;_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&#038;_nc_zt=24&#038;_nc_ht=scontent-gig4-1.xx&#038;_nc_gid=AoBFJeGrT1hVaew_6rchkQ&#038;oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&#038;oe=689E923C\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&#038;_nc_cat=111&#038;ccb=1-7&#038;_nc_sid=f907e8&#038;_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&#038;_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&#038;_nc_zt=24&#038;_nc_ht=scontent-gig4-1.xx&#038;_nc_gid=AoBFJeGrT1hVaew_6rchkQ&#038;oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&#038;oe=689E923C\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-08-31T02:08:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-08-31T02:10:46+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sob nova dire\u00e7\u00e3o, Espeto\u2019s &amp; Cia atrai clientela no Safira - A Not\u00edcia Online\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O Espeto\u2019s &amp; Cia \u2013 Bar e Lanchonete, localizado na Avenida Silv\u00e9rio Campos, n\u00famero 510, no Bairro Safira, agora est\u00e1 sob a dire\u00e7\u00e3o do empres\u00e1rio Felipe. O local, que oferece cerveja gelada e espetinhos variados, tamb\u00e9m realiza entrega em domic\u00edlio de segunda a sexta-feira, a partir das 16h.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&amp;_nc_cat=111&amp;ccb=1-7&amp;_nc_sid=f907e8&amp;_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&amp;_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&amp;_nc_zt=24&amp;_nc_ht=scontent-gig4-1.xx&amp;_nc_gid=AoBFJeGrT1hVaew_6rchkQ&amp;oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&amp;oe=689E923C\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#blogposting\",\"name\":\"Sob nova dire\\u00e7\\u00e3o, Espeto\\u2019s & Cia atrai clientela no Safira - A Not\\u00edcia Online\",\"headline\":\"Sob nova dire\\u00e7\\u00e3o, Espeto\\u2019s &#038; Cia atrai clientela no Safira\",\"author\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/author\\\/juliana\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/WhatsApp-Image-2018-08-28-at-17.34.02-1.jpeg\",\"width\":890,\"height\":667},\"datePublished\":\"2018-08-30T23:08:37-03:00\",\"dateModified\":\"2018-08-30T23:10:46-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#webpage\"},\"articleSection\":\"Blog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#listItem\",\"name\":\"Sob nova dire\\u00e7\\u00e3o, Espeto\\u2019s &#038; Cia atrai clientela no Safira\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#listItem\",\"position\":3,\"name\":\"Sob nova dire\\u00e7\\u00e3o, Espeto\\u2019s &#038; Cia atrai clientela no Safira\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/#organization\",\"name\":\"A Not\\u00edcia Online\",\"description\":\"Noticias de Muria\\u00e9 e regi\\u00e3o\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/scontent-gig4-1.xx.fbcdn.net\\\/v\\\/t39.30808-1\\\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&_nc_cat=111&ccb=1-7&_nc_sid=f907e8&_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&_nc_zt=24&_nc_ht=scontent-gig4-1.xx&_nc_gid=AoBFJeGrT1hVaew_6rchkQ&oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&oe=689E923C\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/author\\\/juliana\\\/#author\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/author\\\/juliana\\\/\",\"name\":\"Juliana Laviola\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8d45f5c699b100dfaf0e543582f38f38bf94cb7ae3a5e9abf8d891a34773335?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juliana Laviola\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#webpage\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/\",\"name\":\"Sob nova dire\\u00e7\\u00e3o, Espeto\\u2019s & Cia atrai clientela no Safira - A Not\\u00edcia Online\",\"description\":\"O Espeto\\u2019s & Cia \\u2013 Bar e Lanchonete, localizado na Avenida Silv\\u00e9rio Campos, n\\u00famero 510, no Bairro Safira, agora est\\u00e1 sob a dire\\u00e7\\u00e3o do empres\\u00e1rio Felipe. O local, que oferece cerveja gelada e espetinhos variados, tamb\\u00e9m realiza entrega em domic\\u00edlio de segunda a sexta-feira, a partir das 16h.\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/author\\\/juliana\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/author\\\/juliana\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/WhatsApp-Image-2018-08-28-at-17.34.02-1.jpeg\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#mainImage\",\"width\":890,\"height\":667},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\\\/#mainImage\"},\"datePublished\":\"2018-08-30T23:08:37-03:00\",\"dateModified\":\"2018-08-30T23:10:46-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/\",\"name\":\"A Not\\u00edcia Online\",\"description\":\"Noticias de Muria\\u00e9 e regi\\u00e3o\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sob nova dire\u00e7\u00e3o, Espeto\u2019s & Cia atrai clientela no Safira - A Not\u00edcia Online","description":"O Espeto\u2019s & Cia \u2013 Bar e Lanchonete, localizado na Avenida Silv\u00e9rio Campos, n\u00famero 510, no Bairro Safira, agora est\u00e1 sob a dire\u00e7\u00e3o do empres\u00e1rio Felipe. O local, que oferece cerveja gelada e espetinhos variados, tamb\u00e9m realiza entrega em domic\u00edlio de segunda a sexta-feira, a partir das 16h.","canonical_url":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#blogposting","name":"Sob nova dire\u00e7\u00e3o, Espeto\u2019s & Cia atrai clientela no Safira - A Not\u00edcia Online","headline":"Sob nova dire\u00e7\u00e3o, Espeto\u2019s &#038; Cia atrai clientela no Safira","author":{"@id":"https:\/\/anoticiaonline.com.br\/site\/author\/juliana\/#author"},"publisher":{"@id":"https:\/\/anoticiaonline.com.br\/site\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02-1.jpeg","width":890,"height":667},"datePublished":"2018-08-30T23:08:37-03:00","dateModified":"2018-08-30T23:10:46-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#webpage"},"isPartOf":{"@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#webpage"},"articleSection":"Blog"},{"@type":"BreadcrumbList","@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site#listItem","position":1,"name":"Home","item":"https:\/\/anoticiaonline.com.br\/site","nextItem":{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/#listItem","position":2,"name":"Blog","item":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#listItem","name":"Sob nova dire\u00e7\u00e3o, Espeto\u2019s &#038; Cia atrai clientela no Safira"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#listItem","position":3,"name":"Sob nova dire\u00e7\u00e3o, Espeto\u2019s &#038; Cia atrai clientela no Safira","previousItem":{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/anoticiaonline.com.br\/site\/#organization","name":"A Not\u00edcia Online","description":"Noticias de Muria\u00e9 e regi\u00e3o","url":"https:\/\/anoticiaonline.com.br\/site\/","logo":{"@type":"ImageObject","url":"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&_nc_cat=111&ccb=1-7&_nc_sid=f907e8&_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&_nc_zt=24&_nc_ht=scontent-gig4-1.xx&_nc_gid=AoBFJeGrT1hVaew_6rchkQ&oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&oe=689E923C","@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#organizationLogo"},"image":{"@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/anoticiaonline.com.br\/site\/author\/juliana\/#author","url":"https:\/\/anoticiaonline.com.br\/site\/author\/juliana\/","name":"Juliana Laviola","image":{"@type":"ImageObject","@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b8d45f5c699b100dfaf0e543582f38f38bf94cb7ae3a5e9abf8d891a34773335?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juliana Laviola"}},{"@type":"WebPage","@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#webpage","url":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/","name":"Sob nova dire\u00e7\u00e3o, Espeto\u2019s & Cia atrai clientela no Safira - A Not\u00edcia Online","description":"O Espeto\u2019s & Cia \u2013 Bar e Lanchonete, localizado na Avenida Silv\u00e9rio Campos, n\u00famero 510, no Bairro Safira, agora est\u00e1 sob a dire\u00e7\u00e3o do empres\u00e1rio Felipe. O local, que oferece cerveja gelada e espetinhos variados, tamb\u00e9m realiza entrega em domic\u00edlio de segunda a sexta-feira, a partir das 16h.","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/anoticiaonline.com.br\/site\/#website"},"breadcrumb":{"@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#breadcrumblist"},"author":{"@id":"https:\/\/anoticiaonline.com.br\/site\/author\/juliana\/#author"},"creator":{"@id":"https:\/\/anoticiaonline.com.br\/site\/author\/juliana\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/WhatsApp-Image-2018-08-28-at-17.34.02-1.jpeg","@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#mainImage","width":890,"height":667},"primaryImageOfPage":{"@id":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/#mainImage"},"datePublished":"2018-08-30T23:08:37-03:00","dateModified":"2018-08-30T23:10:46-03:00"},{"@type":"WebSite","@id":"https:\/\/anoticiaonline.com.br\/site\/#website","url":"https:\/\/anoticiaonline.com.br\/site\/","name":"A Not\u00edcia Online","description":"Noticias de Muria\u00e9 e regi\u00e3o","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/anoticiaonline.com.br\/site\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"A Not\u00edcia Online - Noticias de Muria\u00e9 e regi\u00e3o","og:type":"article","og:title":"Sob nova dire\u00e7\u00e3o, Espeto\u2019s &amp; Cia atrai clientela no Safira - A Not\u00edcia Online","og:description":"O Espeto\u2019s &amp; Cia \u2013 Bar e Lanchonete, localizado na Avenida Silv\u00e9rio Campos, n\u00famero 510, no Bairro Safira, agora est\u00e1 sob a dire\u00e7\u00e3o do empres\u00e1rio Felipe. O local, que oferece cerveja gelada e espetinhos variados, tamb\u00e9m realiza entrega em domic\u00edlio de segunda a sexta-feira, a partir das 16h.","og:url":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/","og:image":"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&#038;_nc_cat=111&#038;ccb=1-7&#038;_nc_sid=f907e8&#038;_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&#038;_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&#038;_nc_zt=24&#038;_nc_ht=scontent-gig4-1.xx&#038;_nc_gid=AoBFJeGrT1hVaew_6rchkQ&#038;oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&#038;oe=689E923C","og:image:secure_url":"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&#038;_nc_cat=111&#038;ccb=1-7&#038;_nc_sid=f907e8&#038;_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&#038;_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&#038;_nc_zt=24&#038;_nc_ht=scontent-gig4-1.xx&#038;_nc_gid=AoBFJeGrT1hVaew_6rchkQ&#038;oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&#038;oe=689E923C","article:published_time":"2018-08-31T02:08:37+00:00","article:modified_time":"2018-08-31T02:10:46+00:00","twitter:card":"summary_large_image","twitter:title":"Sob nova dire\u00e7\u00e3o, Espeto\u2019s &amp; Cia atrai clientela no Safira - A Not\u00edcia Online","twitter:description":"O Espeto\u2019s &amp; Cia \u2013 Bar e Lanchonete, localizado na Avenida Silv\u00e9rio Campos, n\u00famero 510, no Bairro Safira, agora est\u00e1 sob a dire\u00e7\u00e3o do empres\u00e1rio Felipe. O local, que oferece cerveja gelada e espetinhos variados, tamb\u00e9m realiza entrega em domic\u00edlio de segunda a sexta-feira, a partir das 16h.","twitter:image":"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&_nc_cat=111&ccb=1-7&_nc_sid=f907e8&_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&_nc_zt=24&_nc_ht=scontent-gig4-1.xx&_nc_gid=AoBFJeGrT1hVaew_6rchkQ&oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&oe=689E923C"},"aioseo_meta_data":{"post_id":"60905","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-08-16 21:32:39","updated":"2025-08-16 21:32:39","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anoticiaonline.com.br\/site\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSob nova dire\u00e7\u00e3o, Espeto\u2019s &amp; Cia atrai clientela no Safira\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/anoticiaonline.com.br\/site"},{"label":"Blog","link":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/"},{"label":"Sob nova dire\u00e7\u00e3o, Espeto\u2019s &#038; Cia atrai clientela no Safira","link":"https:\/\/anoticiaonline.com.br\/site\/sob-nova-direcao-espetos-cia-atrai-clientela-no-safira\/"}],"views":142,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/60905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=60905"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/60905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/60909"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=60905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=60905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=60905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}