{"id":60831,"date":"2018-08-30T20:08:55","date_gmt":"2018-08-30T23:08:55","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=60831"},"modified":"2018-08-30T20:08:55","modified_gmt":"2018-08-30T23:08:55","slug":"carreta-perde-o-controle-e-atinge-poste-no-gaspar","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/","title":{"rendered":"Carreta perde o controle e atinge poste no Gaspar"},"content":{"rendered":"<p><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-5.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-60832\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-5.jpeg\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-5.jpeg 800w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-5-300x169.jpeg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-5-768x432.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar.jpeg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-60833\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar.jpeg\" alt=\"\" width=\"800\" height=\"450\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar.jpeg 800w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-300x169.jpeg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-768x432.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-2.jpeg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-60834\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-2.jpeg\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-2.jpeg 800w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-2-300x200.jpeg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-2-768x513.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-3.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-60835\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-3.jpeg\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-3.jpeg 800w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-3-300x200.jpeg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-3-768x513.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-4.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-60836\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-4.jpeg\" alt=\"\" width=\"800\" height=\"534\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-4.jpeg 800w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-4-300x200.jpeg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-4-768x513.jpeg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Um acidente aconteceu na tarde de quinta-feira (30), na BR-116, mais precisamente na entrada do Bairro Gaspar. Segundo informa\u00e7\u00f5es do Corpo de Bombeiros, uma carreta, que transportava pneus, tecidos e autope\u00e7as, perdeu o controle e chocou-se contra um poste de energia que, posteriormente, atingiu uma van.<\/p>\n<p>O motorista da van aguardou a chegada de funcion\u00e1rios da Energisa e do Corpo de Bombeiros para deixar o ve\u00edculo somente ap\u00f3s o desligamento da energia el\u00e9trica. Ningu\u00e9m ficou ferido.<\/p>\n<p>Devido ao acidente, moradores do Bairro Gaspar ficaram sem energia e \u00e1gua temporariamente.<\/p>\n<p>Cr\u00e9ditos: Corpo de Bombeiros<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um acidente aconteceu na tarde de quinta-feira (30), na BR-116, mais precisamente na entrada do Bairro Gaspar. Segundo informa\u00e7\u00f5es do Corpo de Bombeiros, uma carreta, que transportava pneus, tecidos e autope\u00e7as, perdeu o controle e chocou-se contra um poste de energia que, posteriormente, atingiu uma van. O motorista da van aguardou a chegada de funcion\u00e1rios &#8230; <a title=\"Carreta perde o controle e atinge poste no Gaspar\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/\" aria-label=\"Read more about Carreta perde o controle e atinge poste no Gaspar\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":60836,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[45],"tags":[],"class_list":["post-60831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transito"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Um acidente aconteceu na tarde de quinta-feira (30), na BR-116, mais precisamente na entrada do Bairro Gaspar. Segundo informa\u00e7\u00f5es do Corpo de Bombeiros, uma carreta, que transportava pneus, tecidos e autope\u00e7as, perdeu o controle e chocou-se contra um poste de energia que, posteriormente, atingiu uma van. O motorista da van aguardou a chegada de funcion\u00e1rios\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Juliana Laviola\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"A Not\u00edcia Online - Noticias de Muria\u00e9 e regi\u00e3o\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Carreta perde o controle e atinge poste no Gaspar - A Not\u00edcia Online\" \/>\n\t\t<meta property=\"og:description\" content=\"Um acidente aconteceu na tarde de quinta-feira (30), na BR-116, mais precisamente na entrada do Bairro Gaspar. Segundo informa\u00e7\u00f5es do Corpo de Bombeiros, uma carreta, que transportava pneus, tecidos e autope\u00e7as, perdeu o controle e chocou-se contra um poste de energia que, posteriormente, atingiu uma van. O motorista da van aguardou a chegada de funcion\u00e1rios\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&#038;_nc_cat=111&#038;ccb=1-7&#038;_nc_sid=f907e8&#038;_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&#038;_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&#038;_nc_zt=24&#038;_nc_ht=scontent-gig4-1.xx&#038;_nc_gid=AoBFJeGrT1hVaew_6rchkQ&#038;oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&#038;oe=689E923C\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&#038;_nc_cat=111&#038;ccb=1-7&#038;_nc_sid=f907e8&#038;_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&#038;_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&#038;_nc_zt=24&#038;_nc_ht=scontent-gig4-1.xx&#038;_nc_gid=AoBFJeGrT1hVaew_6rchkQ&#038;oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&#038;oe=689E923C\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-08-30T23:08:55+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-08-30T23:08:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Carreta perde o controle e atinge poste no Gaspar - A Not\u00edcia Online\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Um acidente aconteceu na tarde de quinta-feira (30), na BR-116, mais precisamente na entrada do Bairro Gaspar. Segundo informa\u00e7\u00f5es do Corpo de Bombeiros, uma carreta, que transportava pneus, tecidos e autope\u00e7as, perdeu o controle e chocou-se contra um poste de energia que, posteriormente, atingiu uma van. O motorista da van aguardou a chegada de funcion\u00e1rios\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&amp;_nc_cat=111&amp;ccb=1-7&amp;_nc_sid=f907e8&amp;_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&amp;_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&amp;_nc_zt=24&amp;_nc_ht=scontent-gig4-1.xx&amp;_nc_gid=AoBFJeGrT1hVaew_6rchkQ&amp;oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&amp;oe=689E923C\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#blogposting\",\"name\":\"Carreta perde o controle e atinge poste no Gaspar - A Not\\u00edcia Online\",\"headline\":\"Carreta perde o controle e atinge poste no Gaspar\",\"author\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/author\\\/juliana\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-4.jpeg\",\"width\":800,\"height\":534},\"datePublished\":\"2018-08-30T20:08:55-03:00\",\"dateModified\":\"2018-08-30T20:08:55-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#webpage\"},\"articleSection\":\"Tr\\u00e2nsito\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/transito\\\/#listItem\",\"name\":\"Tr\\u00e2nsito\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/transito\\\/#listItem\",\"position\":3,\"name\":\"Tr\\u00e2nsito\",\"item\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/transito\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#listItem\",\"name\":\"Carreta perde o controle e atinge poste no Gaspar\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#listItem\",\"position\":4,\"name\":\"Carreta perde o controle e atinge poste no Gaspar\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/categoria\\\/muriae\\\/transito\\\/#listItem\",\"name\":\"Tr\\u00e2nsito\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/#organization\",\"name\":\"A Not\\u00edcia Online\",\"description\":\"Noticias de Muria\\u00e9 e regi\\u00e3o\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/scontent-gig4-1.xx.fbcdn.net\\\/v\\\/t39.30808-1\\\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&_nc_cat=111&ccb=1-7&_nc_sid=f907e8&_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&_nc_zt=24&_nc_ht=scontent-gig4-1.xx&_nc_gid=AoBFJeGrT1hVaew_6rchkQ&oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&oe=689E923C\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/author\\\/juliana\\\/#author\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/author\\\/juliana\\\/\",\"name\":\"Juliana Laviola\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b8d45f5c699b100dfaf0e543582f38f38bf94cb7ae3a5e9abf8d891a34773335?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Juliana Laviola\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#webpage\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/\",\"name\":\"Carreta perde o controle e atinge poste no Gaspar - A Not\\u00edcia Online\",\"description\":\"Um acidente aconteceu na tarde de quinta-feira (30), na BR-116, mais precisamente na entrada do Bairro Gaspar. Segundo informa\\u00e7\\u00f5es do Corpo de Bombeiros, uma carreta, que transportava pneus, tecidos e autope\\u00e7as, perdeu o controle e chocou-se contra um poste de energia que, posteriormente, atingiu uma van. O motorista da van aguardou a chegada de funcion\\u00e1rios\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/author\\\/juliana\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/author\\\/juliana\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-4.jpeg\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#mainImage\",\"width\":800,\"height\":534},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\\\/#mainImage\"},\"datePublished\":\"2018-08-30T20:08:55-03:00\",\"dateModified\":\"2018-08-30T20:08:55-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/\",\"name\":\"A Not\\u00edcia Online\",\"description\":\"Noticias de Muria\\u00e9 e regi\\u00e3o\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/anoticiaonline.com.br\\\/site\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Carreta perde o controle e atinge poste no Gaspar - A Not\u00edcia Online","description":"Um acidente aconteceu na tarde de quinta-feira (30), na BR-116, mais precisamente na entrada do Bairro Gaspar. Segundo informa\u00e7\u00f5es do Corpo de Bombeiros, uma carreta, que transportava pneus, tecidos e autope\u00e7as, perdeu o controle e chocou-se contra um poste de energia que, posteriormente, atingiu uma van. O motorista da van aguardou a chegada de funcion\u00e1rios","canonical_url":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#blogposting","name":"Carreta perde o controle e atinge poste no Gaspar - A Not\u00edcia Online","headline":"Carreta perde o controle e atinge poste no Gaspar","author":{"@id":"https:\/\/anoticiaonline.com.br\/site\/author\/juliana\/#author"},"publisher":{"@id":"https:\/\/anoticiaonline.com.br\/site\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-4.jpeg","width":800,"height":534},"datePublished":"2018-08-30T20:08:55-03:00","dateModified":"2018-08-30T20:08:55-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#webpage"},"isPartOf":{"@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#webpage"},"articleSection":"Tr\u00e2nsito"},{"@type":"BreadcrumbList","@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site#listItem","position":1,"name":"Home","item":"https:\/\/anoticiaonline.com.br\/site","nextItem":{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/#listItem","position":2,"name":"Blog","item":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/transito\/#listItem","name":"Tr\u00e2nsito"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/transito\/#listItem","position":3,"name":"Tr\u00e2nsito","item":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/transito\/","nextItem":{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#listItem","name":"Carreta perde o controle e atinge poste no Gaspar"},"previousItem":{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#listItem","position":4,"name":"Carreta perde o controle e atinge poste no Gaspar","previousItem":{"@type":"ListItem","@id":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/transito\/#listItem","name":"Tr\u00e2nsito"}}]},{"@type":"Organization","@id":"https:\/\/anoticiaonline.com.br\/site\/#organization","name":"A Not\u00edcia Online","description":"Noticias de Muria\u00e9 e regi\u00e3o","url":"https:\/\/anoticiaonline.com.br\/site\/","logo":{"@type":"ImageObject","url":"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&_nc_cat=111&ccb=1-7&_nc_sid=f907e8&_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&_nc_zt=24&_nc_ht=scontent-gig4-1.xx&_nc_gid=AoBFJeGrT1hVaew_6rchkQ&oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&oe=689E923C","@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#organizationLogo"},"image":{"@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/anoticiaonline.com.br\/site\/author\/juliana\/#author","url":"https:\/\/anoticiaonline.com.br\/site\/author\/juliana\/","name":"Juliana Laviola","image":{"@type":"ImageObject","@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/b8d45f5c699b100dfaf0e543582f38f38bf94cb7ae3a5e9abf8d891a34773335?s=96&d=mm&r=g","width":96,"height":96,"caption":"Juliana Laviola"}},{"@type":"WebPage","@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#webpage","url":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/","name":"Carreta perde o controle e atinge poste no Gaspar - A Not\u00edcia Online","description":"Um acidente aconteceu na tarde de quinta-feira (30), na BR-116, mais precisamente na entrada do Bairro Gaspar. Segundo informa\u00e7\u00f5es do Corpo de Bombeiros, uma carreta, que transportava pneus, tecidos e autope\u00e7as, perdeu o controle e chocou-se contra um poste de energia que, posteriormente, atingiu uma van. O motorista da van aguardou a chegada de funcion\u00e1rios","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/anoticiaonline.com.br\/site\/#website"},"breadcrumb":{"@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#breadcrumblist"},"author":{"@id":"https:\/\/anoticiaonline.com.br\/site\/author\/juliana\/#author"},"creator":{"@id":"https:\/\/anoticiaonline.com.br\/site\/author\/juliana\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2018\/08\/Carreta-perde-o-controle-e-atinge-poste-no-Gaspar-4.jpeg","@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#mainImage","width":800,"height":534},"primaryImageOfPage":{"@id":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/#mainImage"},"datePublished":"2018-08-30T20:08:55-03:00","dateModified":"2018-08-30T20:08:55-03:00"},{"@type":"WebSite","@id":"https:\/\/anoticiaonline.com.br\/site\/#website","url":"https:\/\/anoticiaonline.com.br\/site\/","name":"A Not\u00edcia Online","description":"Noticias de Muria\u00e9 e regi\u00e3o","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/anoticiaonline.com.br\/site\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"A Not\u00edcia Online - Noticias de Muria\u00e9 e regi\u00e3o","og:type":"article","og:title":"Carreta perde o controle e atinge poste no Gaspar - A Not\u00edcia Online","og:description":"Um acidente aconteceu na tarde de quinta-feira (30), na BR-116, mais precisamente na entrada do Bairro Gaspar. Segundo informa\u00e7\u00f5es do Corpo de Bombeiros, uma carreta, que transportava pneus, tecidos e autope\u00e7as, perdeu o controle e chocou-se contra um poste de energia que, posteriormente, atingiu uma van. O motorista da van aguardou a chegada de funcion\u00e1rios","og:url":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/","og:image":"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&#038;_nc_cat=111&#038;ccb=1-7&#038;_nc_sid=f907e8&#038;_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&#038;_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&#038;_nc_zt=24&#038;_nc_ht=scontent-gig4-1.xx&#038;_nc_gid=AoBFJeGrT1hVaew_6rchkQ&#038;oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&#038;oe=689E923C","og:image:secure_url":"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&#038;_nc_cat=111&#038;ccb=1-7&#038;_nc_sid=f907e8&#038;_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&#038;_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&#038;_nc_zt=24&#038;_nc_ht=scontent-gig4-1.xx&#038;_nc_gid=AoBFJeGrT1hVaew_6rchkQ&#038;oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&#038;oe=689E923C","article:published_time":"2018-08-30T23:08:55+00:00","article:modified_time":"2018-08-30T23:08:55+00:00","twitter:card":"summary_large_image","twitter:title":"Carreta perde o controle e atinge poste no Gaspar - A Not\u00edcia Online","twitter:description":"Um acidente aconteceu na tarde de quinta-feira (30), na BR-116, mais precisamente na entrada do Bairro Gaspar. Segundo informa\u00e7\u00f5es do Corpo de Bombeiros, uma carreta, que transportava pneus, tecidos e autope\u00e7as, perdeu o controle e chocou-se contra um poste de energia que, posteriormente, atingiu uma van. O motorista da van aguardou a chegada de funcion\u00e1rios","twitter:image":"https:\/\/scontent-gig4-1.xx.fbcdn.net\/v\/t39.30808-1\/270437624_4564083193639691_6907940295614233970_n.jpg?stp=dst-jpg_s200x200_tt6&_nc_cat=111&ccb=1-7&_nc_sid=f907e8&_nc_ohc=SM1wRlP3lJwQ7kNvwEPuBYA&_nc_oc=AdnqrjDN_BNjSSHWO-GbkIWH6fkGMLw4bqvL_NH6e2wMveX7G-rP2dAqsDSq1mJMOaY&_nc_zt=24&_nc_ht=scontent-gig4-1.xx&_nc_gid=AoBFJeGrT1hVaew_6rchkQ&oh=00_AfX7QmFGhQhG2jAllVgXCiM1ZrWgvtp80-Bfppyexh1QEg&oe=689E923C"},"aioseo_meta_data":{"post_id":"60831","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-08-16 21:32:38","updated":"2025-08-16 21:32:38","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anoticiaonline.com.br\/site\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/transito\/\" title=\"Tr\u00e2nsito\">Tr\u00e2nsito<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCarreta perde o controle e atinge poste no Gaspar\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/anoticiaonline.com.br\/site"},{"label":"Blog","link":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/"},{"label":"Tr\u00e2nsito","link":"https:\/\/anoticiaonline.com.br\/site\/categoria\/muriae\/transito\/"},{"label":"Carreta perde o controle e atinge poste no Gaspar","link":"https:\/\/anoticiaonline.com.br\/site\/carreta-perde-o-controle-e-atinge-poste-no-gaspar\/"}],"views":145,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/60831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=60831"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/60831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/60836"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=60831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=60831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=60831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}