{"id":44658,"date":"2017-11-10T10:23:06","date_gmt":"2017-11-10T13:23:06","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=44658"},"modified":"2017-11-10T10:23:07","modified_gmt":"2017-11-10T13:23:07","slug":"a-vida-e-breve","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/a-vida-e-breve\/","title":{"rendered":"A vida \u00e9 breve"},"content":{"rendered":"<p>Adellunar Marge<\/p>\n<p>Muito j\u00e1 se falou sobre a brevidade da vida, principalmente quando se compara com a hip\u00f3tese de haver uma vida espiritual eterna. \u00c9 que o tempo passa r\u00e1pido, ainda que deixando profundas marcas nos seres vivos, envelhecendo-os, debilitando-os at\u00e9 o legado final da morte. Quem n\u00e3o queria passar desta vida t\u00e3o ef\u00eamera, t\u00e3o breve, para uma outra eterna e, principalmente, imune \u00e0s a\u00e7\u00f5es do tempo?<\/p>\n<p>Aur\u00e9lio Agostinho, de enorme influ\u00eancia no pensamento crist\u00e3o da Idade M\u00e9dia, nasceu em Tagasta (atual Souq-Ahras, na Arg\u00e9lia) no ano 354 e faleceu em Hipona (Num\u00eddia), no ano 430. O grande problema que ocupou sem d\u00favida alguma o pensamento de Agostino, foi o problema do mal. Conceitu\u00e1-lo e tentar super\u00e1-lo foi a sua principal luta.<\/p>\n<p>Jostein Gaarder, fil\u00f3sofo e escritor noruegu\u00eas, baseado na c\u00f3pia de manuscritos de Flora Em\u00edlia, concubina durante muitos anos de Aur\u00e9lio Agostinho, adquiridos em um Sebo de Buenos Aires, escreveu o pequeno mas ambicioso livro de pouco mais de 70 p\u00e1ginas, intitulado \u201cVita Brevis\u201d.<\/p>\n<p>Vita Brevis, portanto, \u00e9 uma compila\u00e7\u00e3o de partes de dezenas de folhas de pergaminho escritos por Flora Em\u00edlia relatando todo o drama do amor entre ela e Aur\u00e9lio Agostino, uma rela\u00e7\u00e3o sempre rejeitada por M\u00f4nica, a m\u00e3e de Agostinho e que encontrou sua maior barreira nas futuras convic\u00e7\u00f5es religiosas do te\u00f3logo crist\u00e3o. Para Flora Em\u00edlia, Agostinho a cita em apenas duas frases em sua obra \u201cConfiss\u00f5es\u201d e ainda assim, sem mencionar o seu nome.<\/p>\n<p>Em sua juventude, Agostinho era ligado aos prazeres da vida, principalmente aos prazeres sensuais e, embora jovem e desajeitado nessas rela\u00e7\u00f5es, conforme confidencia Flora Em\u00edlia, \u201cpossu\u00eda uma sensualidade irrefre\u00e1vel, distribu\u00edda por todo o corpo\u201d. De um relacionamento que se estendeu por doze anos, Agostinho e Flora tiveram o filho Adeodato, que Agostinho se referia sempre como \u201cfruto do meu pecado\u201d. Adeotado foi arrebatado da companhia de Flora Em\u00edlia por Agostinho quando ele a mandou de volta para Cartago.<\/p>\n<p>O conte\u00fado de \u201cVita Brevis\u201d, relatado por Jostein Gaarder como exposto por Flora no latim pr\u00f3prio do quarto e quinto s\u00e9culos da era crist\u00e3, \u00e9 o desabafo de uma mulher, como amante e m\u00e3e. Ela condena o abandono a que foi relegada e a condena\u00e7\u00e3o do seu amor, culpando M\u00f4nica, a m\u00e3e de Agostinho, pela separa\u00e7\u00e3o. Agostinho foi sempre atormentado pelos chamados prazeres sens\u00edveis, condenando os prazeres da audi\u00e7\u00e3o, do olfato e da vis\u00e3o. Recusava-se a sentir o odor de um perfume, a ouvir a beleza da m\u00fasica de um salmo, ou a contemplar a beleza de uma flor. Flora, ao contr\u00e1rio, ama a vida, o cantar dos p\u00e1ssaros e entende que essas manifesta\u00e7\u00f5es do belo foram criadas t\u00e3o divinamente quanto o sexo e que \u00e9 direito de qualquer ser humano se deleitar com toda a obra da cria\u00e7\u00e3o. Flora acusa M\u00f4nica, a m\u00e3e de Aurel, como ela o chamava, de ter provocado a separa\u00e7\u00e3o dos dois. M\u00f4nica queria para o filho Agostinho um casamento com uma mo\u00e7a de conceituada posi\u00e7\u00e3o social, mas a menina pedida em casamento tinha apenas 11 anos e, pela lei da \u00e9poca, era preciso esperar mais dois anos para que o casamento se realizasse. Segundo Flora, em uma Primavera, quando ela foi a Mil\u00e3o para se encontrar com Agostinho, M\u00f4nica foi \u00e0s pressas para l\u00e1 para se colocar entre ambos e desfazer a uni\u00e3o. Segundo a redatora das cartas, Agostinho p\u00f5e um limite em suas \u201cConfiss\u00f5es\u201d, n\u00e3o relatando as faltas mais graves, entre elas, a nega\u00e7\u00e3o daquele amor que os unira por doze anos. Assim, Flora foi separada do seu grande amor Aurel, como ela o chamava. Um homem que, segundo ela, vivia numa luta constante contra as \u201ctenta\u00e7\u00f5es da carne\u201d e dominado por uma pr\u00e1tica obcecada de jejuns e de mortifica\u00e7\u00f5es.<\/p>\n<p>Flora Em\u00edlia jamais se ligou a outro amor. N\u00e3o se deixou batizar, talvez por um sentimento interior de indigna\u00e7\u00e3o, mas aprimorou sua cultura, o seu saber, exercendo a fun\u00e7\u00e3o de professora de Ret\u00f3rica. Adeodato, o \u201cfruto do pecado\u201d, como era chamado por Agostinho, morreu com pouco mais de dezessete anos. Para ele sim, a vida foi bastante breve&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adellunar Marge Muito j\u00e1 se falou sobre a brevidade da vida, principalmente quando se compara com a hip\u00f3tese de haver uma vida espiritual eterna. \u00c9 que o tempo passa r\u00e1pido, ainda que deixando profundas marcas nos seres vivos, envelhecendo-os, debilitando-os at\u00e9 o legado final da morte. Quem n\u00e3o queria passar desta vida t\u00e3o ef\u00eamera, t\u00e3o &#8230; <a title=\"A vida \u00e9 breve\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/a-vida-e-breve\/\" aria-label=\"Read more about A vida \u00e9 breve\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31,36],"tags":[329,1524,1045,1525,1289],"class_list":["post-44658","post","type-post","status-publish","format-standard","hentry","category-colunistas","category-logos-adellunar-marge","tag-adellunar-marge","tag-breve","tag-colunar","tag-texto","tag-vida"],"acf":[],"aioseo_notices":[],"views":123,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/44658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=44658"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/44658\/revisions"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=44658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=44658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=44658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}