{"id":44359,"date":"2017-11-01T19:58:59","date_gmt":"2017-11-01T22:58:59","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=44359"},"modified":"2017-11-01T20:25:41","modified_gmt":"2017-11-01T23:25:41","slug":"escola-pinguinho-de-gente-realiza-sua-xxvi-semana-de-arte-2017","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/escola-pinguinho-de-gente-realiza-sua-xxvi-semana-de-arte-2017\/","title":{"rendered":"Escola Pinguinho de Gente realiza sua XXVI Semana de Arte 2017"},"content":{"rendered":"<p><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0457.jpg\"><\/a><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0550.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-44367\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0550.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0550.jpg 640w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0550-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0457.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-44366\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0457.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0457.jpg 640w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0457-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0564.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-44368\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0564.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0564.jpg 640w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0564-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0579.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44369\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0579.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0579.jpg 640w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0579-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0595.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-44370\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0595.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0595.jpg 640w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/11\/DSC_0595-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>A Escola Pinguinho de Gente realizou sua XXVI Semana de Arte, que, este ano, abordou o tema \u201cVivendo a Arte \u2013 Conhecendo o Mundo\u201d. O evento, que aconteceu entres os dias 24 e 28 de outubro, envolveu os professores, os funcion\u00e1rios, a dire\u00e7\u00e3o da escola e contou com a presen\u00e7a dos familiares dos alunos.<\/p>\n<p>Maria Em\u00edlia Martins Baroni, orientadora da escola, disse que a XXVI Semana de Arte \u00e9 importante para que as crian\u00e7as possam conhecer a hist\u00f3ria de outros pa\u00edses, outros valores e outros idiomas.<\/p>\n<p>\u201cA Semana de Arte j\u00e1 faz parte do calend\u00e1rio da Pinguinho de Gente e, por isso, as crian\u00e7as ficam na expectativa para saber quais os temas ser\u00e3o abordados durante o evento. Os alunos participam sempre com muito entusiasmo e curiosidade querendo sempre saber mais sobre determinados assuntos\u201d, conta.<\/p>\n<p>De acordo com Maria Em\u00edlia, este ano o projeto contou com a atividade \u201cViajando com os Pais\u201d, que tratou de uma roda informativa na qual os alunos falavam para os familiares sobre os pa\u00edses que estudaram.<\/p>\n<p>\u201cA realiza\u00e7\u00e3o de mais uma Semana de Arte \u00e9 que temos a certeza de que estamos incentivando os alunos a ampliar seus conhecimentos sobre o mundo, comparando situa\u00e7\u00f5es e desenvolvendo opini\u00f5es a respeito. Nosso compromisso n\u00e3o para aqui. Estamos em constante atualiza\u00e7\u00e3o e preparando novidades para o pr\u00f3ximo ano. Nossas matr\u00edculas est\u00e3o abertas e contamos com a presen\u00e7a de todos voc\u00eas\u201d, finaliza.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"ngg_displayed_gallery mceItem\" src=\"https:\/\/anoticiaonline.com.br\/site\/nextgen-attach_to_post\/preview\/id--44438\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Escola Pinguinho de Gente realizou sua XXVI Semana de Arte, que, este ano, abordou o tema \u201cVivendo a Arte \u2013 Conhecendo o Mundo\u201d. O evento, que aconteceu entres os dias 24 e 28 de outubro, envolveu os professores, os funcion\u00e1rios, a dire\u00e7\u00e3o da escola e contou com a presen\u00e7a dos familiares dos alunos. Maria &#8230; <a title=\"Escola Pinguinho de Gente realiza sua XXVI Semana de Arte 2017\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/escola-pinguinho-de-gente-realiza-sua-xxvi-semana-de-arte-2017\/\" aria-label=\"Read more about Escola Pinguinho de Gente realiza sua XXVI Semana de Arte 2017\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":44367,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[165,587,1475,1478,1480,1481,74,1482,1479,1477,1476],"class_list":["post-44359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gerais","tag-educacao","tag-escola","tag-escola-pinguinho-de-gente","tag-maria-emilia-martins-baroni","tag-maternal","tag-matricula","tag-muriae","tag-pinguinho-de-gente","tag-viajando-com-os-pais","tag-vivendo-a-arte-conhecendo-o-mundo","tag-xxvi-semana-de-arte"],"acf":[],"aioseo_notices":[],"views":135,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/44359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=44359"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/44359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/44367"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=44359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=44359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=44359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}