{"id":43260,"date":"2017-10-27T10:10:34","date_gmt":"2017-10-27T13:10:34","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=43260"},"modified":"2017-10-27T10:11:30","modified_gmt":"2017-10-27T13:11:30","slug":"ii-edicao-do-talentos-do-nosso-bairro-e-realizada-no-gaspar","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/ii-edicao-do-talentos-do-nosso-bairro-e-realizada-no-gaspar\/","title":{"rendered":"II Edi\u00e7\u00e3o do \u201cTalentos do Nosso Bairro\u201d \u00e9 realizada no Gaspar"},"content":{"rendered":"<p><em><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/foto-capa.jpg\"><\/a><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/foto-capa.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-43262\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/foto-capa.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/foto-capa.jpg 640w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/foto-capa-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/DSC_0178.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-43261\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/DSC_0178.jpg\" alt=\"\" width=\"640\" height=\"426\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/DSC_0178.jpg 640w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/DSC_0178-300x200.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a>Evento contou com desfile de looks da loja M\u00e1rcia Modas<\/em><\/p>\n<p>A Associa\u00e7\u00e3o de Moradores do Bairro Gaspar promoveu a II Edi\u00e7\u00e3o do \u201cTalentos do Nosso Bairro\u201d, na tarde de domingo (22). O objetivo do evento foi incentivar e apresentar moradores da comunidade que se destacam em diversas \u00e1reas, como a dan\u00e7a, a m\u00fasica e a culin\u00e1ria.<\/p>\n<p>O \u201cTalentos do Nosso Bairro\u201d, que teve sua primeira edi\u00e7\u00e3o no ano de 2015, contou com um palco para receber as atra\u00e7\u00f5es de m\u00fasica e de dan\u00e7a, todas apresentadas por moradores do pr\u00f3prio Gaspar.<\/p>\n<p>A Rua Sete de Setembro ficou movimentada com a presen\u00e7a de fam\u00edlias inteiras e de pessoas de todas as idades para visitar as barraquinhas de doces, del\u00edcias e artesanatos preparadas pelos talentosos moradores do bairro.<\/p>\n<p>Al\u00e9m dos shows de talentos, o evento contou tamb\u00e9m com um concurso, que premiou a \u201cBeleza Negra\u201d, no qual participaram jovens que encantaram a todos com a plenitude da afro-descend\u00eancia e com um sorteio de um aparelho celular.<\/p>\n<p>Tamb\u00e9m foi organizado um desfile da cole\u00e7\u00e3o Primavera\/Ver\u00e3o pela loja M\u00e1rcia Modas, com modelos apresentando cinco looks masculino, feminino e infanto-juvenil.<\/p>\n<p>A loja, localizada na Rua S\u00e3o Jo\u00e3o Batista, n\u00famero 25, \u00e9 propriedade da empres\u00e1ria M\u00e1rcia Helena Rodrigues Levate e funciona no Bairro Gaspar h\u00e1 oito anos oferecendo descontos \u00e0 vista, compras no cart\u00e3o de cr\u00e9dito e no credi\u00e1rio.<\/p>\n<p>Roselene Duarte de Souza, presidente da Associa\u00e7\u00e3o de Moradores do Bairro Gaspar, disse que esta foi a oportunidade de resgatar a autoestima dos moradores, principalmente dos mais jovens.<\/p>\n<p>\u201cNossa inten\u00e7\u00e3o era despertar os talentos que existem em nosso bairro, que antes era conhecido pelos acidentes ocorridos pr\u00f3ximo ao trecho da BR e demais fatores negativos. Nas \u00faltimas semanas n\u00e3o se falava em outra coisa a n\u00e3o ser este evento. Todos estavam ansiosos para preparar aquilo que faziam de melhor\u201d, diz.<\/p>\n<p>De acordo com Roselene, cada um foi convidado a mostrar o seu talento. \u201cNosso locutor do evento foi o Walderrama, morador conhecido em toda a cidade. Tivemos tamb\u00e9m o apoio do UNIFAMINAS, atrav\u00e9s dos alunos de Arquitetura, que fizeram m\u00e1scaras para a crian\u00e7ada. Espero que possamos repetir o evento nos pr\u00f3ximos anos\u201d, conta.<\/p>\n<p>O vereador Ivanir do Gaspar esteve presente no \u201cTalentos do Nosso Bairro\u201d e aproveitou para cumprimentar todos os envolvidos. \u201cParbenizo \u00e0 moradora Roselene Duarte pela iniciativa e agrade\u00e7o aos participantes pela disponibilidade e participa\u00e7\u00e3o\u201d, diz.<\/p>\n<p><img decoding=\"async\" class=\"ngg_displayed_gallery mceItem\" src=\"https:\/\/anoticiaonline.com.br\/site\/nextgen-attach_to_post\/preview\/id--43317\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento contou com desfile de looks da loja M\u00e1rcia Modas A Associa\u00e7\u00e3o de Moradores do Bairro Gaspar promoveu a II Edi\u00e7\u00e3o do \u201cTalentos do Nosso Bairro\u201d, na tarde de domingo (22). O objetivo do evento foi incentivar e apresentar moradores da comunidade que se destacam em diversas \u00e1reas, como a dan\u00e7a, a m\u00fasica e a &#8230; <a title=\"II Edi\u00e7\u00e3o do \u201cTalentos do Nosso Bairro\u201d \u00e9 realizada no Gaspar\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/ii-edicao-do-talentos-do-nosso-bairro-e-realizada-no-gaspar\/\" aria-label=\"Read more about II Edi\u00e7\u00e3o do \u201cTalentos do Nosso Bairro\u201d \u00e9 realizada no Gaspar\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":43262,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[421],"class_list":["post-43260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gerais","tag-gaspar"],"acf":[],"aioseo_notices":[],"views":125,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/43260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=43260"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/43260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/43262"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=43260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=43260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=43260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}