{"id":43045,"date":"2017-10-23T15:15:45","date_gmt":"2017-10-23T18:15:45","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=43045"},"modified":"2017-10-23T15:15:45","modified_gmt":"2017-10-23T18:15:45","slug":"sociarte-20-10","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/sociarte-20-10\/","title":{"rendered":"SOCIARTE 20.10"},"content":{"rendered":"<p><strong><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Comemora\u00e7\u00e3o-dupla.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-43046\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Comemora\u00e7\u00e3o-dupla.jpg\" alt=\"\" width=\"266\" height=\"400\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Comemora\u00e7\u00e3o-dupla.jpg 426w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Comemora\u00e7\u00e3o-dupla-200x300.jpg 200w\" sizes=\"(max-width: 266px) 100vw, 266px\" \/><\/a>Comemora\u00e7\u00e3o dupla<\/strong><\/p>\n<p>Os pais Fernando Oliveira e Regiane Bittencourt, da Drogaria Nova, comemoraram o anivers\u00e1rio de 10 anos de sua linda filha, Fernanda Bittencourt, juntamente com o batizado do ca\u00e7ula da fam\u00edlia, o fofo Lorenzo, no dia 15 de outubro, na Ch\u00e1cara do Fernando, na Gameleira. Felicidades para toda a fam\u00edlia! Clique cedido pela Foto Central.<\/p>\n<p><strong><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Casamento-Teresa-e-Devanir.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-43047\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Casamento-Teresa-e-Devanir.jpg\" alt=\"\" width=\"265\" height=\"400\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Casamento-Teresa-e-Devanir.jpg 424w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Casamento-Teresa-e-Devanir-199x300.jpg 199w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><\/a>Casamento Teresa e Devanir<\/strong><\/p>\n<p>Teresa Cristina Quint\u00e3o e Devanir da Silva Chaves uniram-se em matrim\u00f4nio na noite de s\u00e1bado (14), na Igreja S\u00e3o Francisco de Assis, no bairro S\u00e3o Francisco. A recep\u00e7\u00e3o aconteceu no Espa\u00e7o G\u00e1vea. Ela \u00e9 filha de Nilma e Wilton Quint\u00e3o (in memoriam); ele \u00e9 filho de Francisco Chaves (in memoriam) e Nair Chaves (in memoriam). Parab\u00e9ns ao casal!<\/p>\n<p><strong><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Batizado-de-Maria-J\u00falia.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-43048\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Batizado-de-Maria-J\u00falia.jpg\" alt=\"\" width=\"265\" height=\"400\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Batizado-de-Maria-J\u00falia.jpg 424w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Batizado-de-Maria-J\u00falia-199x300.jpg 199w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><\/a>Batizado de Maria J\u00falia<\/strong><\/p>\n<p>A linda Maria J\u00falia Soares Coelho, filha de Cleusa Ar\u00eades Soares e de Marcelo Coelho, foi batizada na Igreja Cat\u00f3lica do bairro Jo\u00e3o XXIII, no \u00faltimo domingo (15), ap\u00f3s a cerim\u00f4nia, fam\u00edlia, amigos e padrinhos se reuniram para uma animada comemora\u00e7\u00e3o. Felicidades, Maria J\u00falia! Foto gentilmente cedida pela Foto Central.<\/p>\n<p><strong><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/5-anos-de-Arthur.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-43049\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/5-anos-de-Arthur-300x211.jpg\" alt=\"\" width=\"400\" height=\"281\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/5-anos-de-Arthur-300x211.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/5-anos-de-Arthur.jpg 640w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>5 anos de Arthur<\/strong><\/p>\n<p>O gatinho Arthur Rodrigues Romero comemorou seu anivers\u00e1rio de 5 anos ao lados dos pais, Washington Romero e L\u00edvia Romero, fam\u00edlia e amigos, no quiosque da AABB. A festa, comemorada no s\u00e1bado (14), teve como tema Os Vingadores. Parab\u00e9ns. Arthur. Foto: Revele Photo.<\/p>\n<p><strong><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Parab\u00e9ns-Cristiane.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-43051\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Parab\u00e9ns-Cristiane-225x300.jpg\" alt=\"\" width=\"300\" height=\"400\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Parab\u00e9ns-Cristiane-225x300.jpg 225w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Parab\u00e9ns-Cristiane.jpg 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Parab\u00e9ns, Cristiane<\/strong><\/p>\n<p>Nossa amiga, Cristiane Cassim, propriet\u00e1ria da Mix Lanches, completou idade nova na \u00faltima quarta-feira (18). N\u00f3s do jornal A Not\u00edcia desejamos muitas felicidades, sa\u00fade e sucesso em sua vida! Parab\u00e9ns!<\/p>\n<p><strong><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/foto-Sonia.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-43050\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/foto-Sonia-300x200.jpeg\" alt=\"\" width=\"400\" height=\"267\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/foto-Sonia-300x200.jpeg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/foto-Sonia.jpeg 640w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>Feliz A<\/strong><strong>nivers\u00e1rio, S\u00f4nia<\/strong><\/p>\n<p>A querida S\u00f4nia Maria Dias de Azevedo comemorou seu anivers\u00e1rio, no s\u00e1bado (14), ao lado de seus amigos e companheiras do Lions Clube Muria\u00e9 Helen Keller, durante a beneficente Noite \u00c1rabe, na AABB. Ela \u00e9 casada com Edmilson Terra de Azevedo e m\u00e3e de Ant\u00f4nio Azevedo Neto e Evelyn Dias de Azevedo. Felicidades, S\u00f4nia!<\/p>\n<p><strong><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Aniversariantes-da-semana.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-43052\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Aniversariantes-da-semana-300x200.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Aniversariantes-da-semana-300x200.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/10\/Aniversariantes-da-semana.jpg 640w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>Aniversariantes da semana<\/strong><strong>\u00a0<\/strong><\/p>\n<p>Tamb\u00e9m durante a Noite \u00c1rabe, do Lions Clube Muria\u00e9 Helen Keller, as companheiras, Mar\u00edlia Pimentel Adriano (ponta esquerda), S\u00f4nia Maria Dias de Azevedo (de preto), Zilma Xavier de Souza (de rosa ao centro) e Suely Ribeiro Damas (de azul), aniversariantes da semana, comemoraram a idade nova, em grande estilo, durante a festa beneficente que aconteceu no s\u00e1bado (14), acompanhadas da presidente Wanderly Torres (esquerda) e Maria Ang\u00e9lica (ponta direita).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comemora\u00e7\u00e3o dupla Os pais Fernando Oliveira e Regiane Bittencourt, da Drogaria Nova, comemoraram o anivers\u00e1rio de 10 anos de sua linda filha, Fernanda Bittencourt, juntamente com o batizado do ca\u00e7ula da fam\u00edlia, o fofo Lorenzo, no dia 15 de outubro, na Ch\u00e1cara do Fernando, na Gameleira. Felicidades para toda a fam\u00edlia! Clique cedido pela Foto &#8230; <a title=\"SOCIARTE 20.10\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/sociarte-20-10\/\" aria-label=\"Read more about SOCIARTE 20.10\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31,38],"tags":[],"class_list":["post-43045","post","type-post","status-publish","format-standard","hentry","category-colunistas","category-sociarte"],"acf":[],"aioseo_notices":[],"views":139,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/43045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=43045"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/43045\/revisions"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=43045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=43045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=43045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}