{"id":41459,"date":"2017-09-30T12:00:52","date_gmt":"2017-09-30T15:00:52","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=41459"},"modified":"2017-09-30T09:47:14","modified_gmt":"2017-09-30T12:47:14","slug":"hsp-realiza-o-1o-simposio-de-cardiologia-intervencionista-para-o-clinico","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/hsp-realiza-o-1o-simposio-de-cardiologia-intervencionista-para-o-clinico\/","title":{"rendered":"HSP realiza o 1\u00ba Simp\u00f3sio de Cardiologia Intervencionista para o Cl\u00ednico"},"content":{"rendered":"<p><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/DSC_1205.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-41506\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/DSC_1205-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/DSC_1205-300x199.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/DSC_1205-290x192.jpg 290w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/DSC_1205.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/DSC_1332.jpg\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-41507\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/DSC_1332-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/DSC_1332-300x199.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/DSC_1332-290x192.jpg 290w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/DSC_1332.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>O Hospital S\u00e3o Paulo de Muria\u00e9 realizou, na noite de sexta-feira (22), o 1\u00ba Simp\u00f3sio de Cardiologia Intervencionista para o Cl\u00ednico, no audit\u00f3rio Dra. Rosemary Francisco Feres, voltado para profissionais e acad\u00eamicos de Medicina. O evento foi organizado pelos m\u00e9dicos: Edivar Pereira de Almeida (Coordenador do Setor de Cardiologia), Leonardo Pereira de Mendon\u00e7a (Coordenador do Setor de Hemodin\u00e2mica) e Carlos Eduardo Felippe F\u00e9res (Presidente do Centro de Estudos) que fazem parte do Corpo Cl\u00ednico do HSP.<\/p>\n<p>Cl\u00e1udio Pompei, m\u00e9dico ortopedista e diretor cl\u00ednico do Hospital S\u00e3o Paulo, esteve presente no Simp\u00f3sio e falou a import\u00e2ncia do evento que fortaleceu a classe m\u00e9dica do HSP e demais institui\u00e7\u00f5es de sa\u00fade da cidade. \u201cAl\u00e9m dos profissionais, temos hoje, em Muria\u00e9, os estudantes de Medicina. Neste evento, recebemos aproximadamente 50 alunos do Unifaminas que vieram participar e aumentar sua bagagem curricular com um grande aproveitamento\u201d, disse.<\/p>\n<p>Cl\u00e1udio Pompei aproveitou para parabenizar o Setor de Cardiologia, atrav\u00e9s de seu representante: Edivar Pereira de Almeida e o coordenador do Setor de Hemodin\u00e2mica, Leonardo Pereira de Mendon\u00e7a, al\u00e9m de todos os membros. \u201cSei o quanto \u00e9 trabalhoso organizar um Simp\u00f3sio. Temos que comemorar junto com os m\u00e9dicos e os funcion\u00e1rios do Hospital S\u00e3o Paulo, mais um evento de sucesso e o quanto de experi\u00eancia temos para trocar\u201d, contou.<\/p>\n<p>Pedro Rabelo de Mesquita Filho, m\u00e9dico anestesista, diretor t\u00e9cnico e vice-diretor cl\u00ednico do HSP, avaliou a import\u00e2ncia deste primeiro Simp\u00f3sio de Cardiologia. \u201cO Hospital S\u00e3o Paulo encontra-se em um momento de renova\u00e7\u00e3o ao integrar os acad\u00eamicos e disponibilizar vagas para os m\u00e9dicos residentes. Esses fatores nos levam um caminho de constante evolu\u00e7\u00e3o, aplicando e adquirindo novos conhecimentos em sintonia com a medicina atual e este evento \u00e9 mais um reflexo disso. Ao final, nossos pacientes ganham atendimento de qualidade, atendimento humanizado e com a aplica\u00e7\u00e3o de novas tecnologias\u201d, contou.<\/p>\n<p>Na abertura, a diretora administrativa do HSP, Rita Pereira, desejou boas-vindas, falou aos presentes sobre as conquistas da entidade e agradeceu ao cardiologista Edivar Pereira de Almeida e, toda a sua equipe, pelo trabalho e pelo primeiro Simp\u00f3sio na \u00e1rea.<\/p>\n<p>Durante a abertura do Simp\u00f3sio, tamb\u00e9m esteve presente o provedor do Hospital, Messias Soares Vardiero, que est\u00e1 \u00e0 frente da institui\u00e7\u00e3o h\u00e1 10 anos.<\/p>\n<p><strong>Sobre o evento &#8211;<\/strong> Com sala cheia, o Simp\u00f3sio abordou temas diversos e recebeu profissionais de diferentes cidades mineiras. O primeiro palestrante foi o m\u00e9dico cardiologista Jos\u00e9 Carlos Faria Garcia, de Belo Horizonte, que falou a respeito do Tratamento Atual nas Les\u00f5es de TCE. Leonardo Pereira de Mendon\u00e7a foi o presidente da mesa e os moderadores foram os m\u00e9dicos cardiologistas: Luciano Sales Lug\u00e3o da Silva, de Al\u00e9m Para\u00edba, e Humberto Vicente Alagia, de Cataguases.<\/p>\n<p>Em sua primeira visita a Muria\u00e9, o cardiologista Jos\u00e9 Carlos Faria Garcia ficou surpreso com a qualidade deste 1\u00ba Simp\u00f3sio. \u201cOs organizadores escolheram muito bem os temas a serem abordados. Fui surpreendido com o n\u00edvel das perguntas vindas da plateia e da mesa. Sem d\u00favida, um evento de alta qualidade que contribui para a medicina e para o hospital\u201d, disse.<\/p>\n<p>A segunda palestra tratou sobre a Abordagem da S\u00edndrome Coronariana Aguda Sem Supra de ST, ministrada pelo cardiologista Cirilo Pereira da Fonseca Neto, tamb\u00e9m de Belo Horizonte. A mesa, presidida por Edivar Pereira de Almeida, tamb\u00e9m contou com a presen\u00e7a dos mediadores: Luiz Ronaldo Pinheiro dos Santos, cardiologista de Recreio, e Carlos Alberto Tassara Perillo, cardiologista de Visconde do Rio Branco.<\/p>\n<p>A terceira palestra da noite abordou a Cardiopatia Cong\u00eanita e quando \u00e9 indicado o fechamento percut\u00e2neo de FOP, CIA e CIV, ministrada pelo m\u00e9dico cardiologista Roberto Max Lopes, de Belo Horizonte. O presidente da mesa foi o m\u00e9dico Jos\u00e9 Santos Mostaro. Os moderadores foram os m\u00e9dicos cardiologistas Leonardo Pereira de Mendon\u00e7a e Erickson Guedes Ferrari, de Muria\u00e9.<\/p>\n<p>\u201cEstenose A\u00f3rtica: TAVI x Cirurgia\u201d foi \u00faltimo assunto apresentado no evento, abordado pelos m\u00e9dicos cardiologista Ricardo Mauro Ghetti Cabral, de Ub\u00e1 e pelo cirurgi\u00e3o cardiovascular Celme da Silva Caetano J\u00fanior. A mesa foi presidida pelo cardiologista C\u00e9zar Ladeira Macedo J\u00fanior e contou com os cardiologistas Jo\u00e3o Manoel da Silva Alves, de Cataguases, e Gustavo Schueler de Aquino, como moderadores.<\/p>\n<p><img decoding=\"async\" class=\"ngg_displayed_gallery mceItem\" src=\"https:\/\/anoticiaonline.com.br\/site\/nextgen-attach_to_post\/preview\/id--41503\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Hospital S\u00e3o Paulo de Muria\u00e9 realizou, na noite de sexta-feira (22), o 1\u00ba Simp\u00f3sio de Cardiologia Intervencionista para o Cl\u00ednico, no audit\u00f3rio Dra. Rosemary Francisco Feres, voltado para profissionais e acad\u00eamicos de Medicina. O evento foi organizado pelos m\u00e9dicos: Edivar Pereira de Almeida (Coordenador do Setor de Cardiologia), Leonardo Pereira de Mendon\u00e7a (Coordenador do &#8230; <a title=\"HSP realiza o 1\u00ba Simp\u00f3sio de Cardiologia Intervencionista para o Cl\u00ednico\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/hsp-realiza-o-1o-simposio-de-cardiologia-intervencionista-para-o-clinico\/\" aria-label=\"Read more about HSP realiza o 1\u00ba Simp\u00f3sio de Cardiologia Intervencionista para o Cl\u00ednico\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":41507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[1225,1223,1227,1226,1224,55,3],"class_list":["post-41459","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gerais","tag-1o-simposio-de-cardiologia-intervencionista-para-o-clinico","tag-coracao","tag-corpo-clinico-do-hsp","tag-dra-rosemary-francisco-feres","tag-hospital-sao-paulo-de-muriae","tag-hsp","tag-slide"],"acf":[],"aioseo_notices":[],"views":162,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/41459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=41459"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/41459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/41507"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=41459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=41459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=41459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}