{"id":40852,"date":"2017-09-21T18:56:57","date_gmt":"2017-09-21T21:56:57","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=40852"},"modified":"2017-09-21T19:02:12","modified_gmt":"2017-09-21T22:02:12","slug":"merendeira-de-sao-francisco-do-gloria-esta-na-final-de-concurso-nacional-do-mec-e-fnde","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/merendeira-de-sao-francisco-do-gloria-esta-na-final-de-concurso-nacional-do-mec-e-fnde\/","title":{"rendered":"Merendeira de S\u00e3o Francisco do Gl\u00f3ria est\u00e1 na final de Concurso Nacional do MEC e FNDE"},"content":{"rendered":"<p><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/Merendeira-de-S\u00e3o-Francisco-do-Gl\u00f3ria-est\u00e1-na-semifinal-de-Concurso-Nacional-do-MEC-e-FNDE-2.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-40857 alignleft\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/Merendeira-de-S\u00e3o-Francisco-do-Gl\u00f3ria-est\u00e1-na-semifinal-de-Concurso-Nacional-do-MEC-e-FNDE-2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/Merendeira-de-S\u00e3o-Francisco-do-Gl\u00f3ria-est\u00e1-na-semifinal-de-Concurso-Nacional-do-MEC-e-FNDE-2-300x225.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/Merendeira-de-S\u00e3o-Francisco-do-Gl\u00f3ria-est\u00e1-na-semifinal-de-Concurso-Nacional-do-MEC-e-FNDE-2.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/Merendeira-de-S\u00e3o-Francisco-do-Gl\u00f3ria-est\u00e1-na-semifinal-de-Concurso-Nacional-do-MEC-e-FNDE.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-40858 alignleft\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/Merendeira-de-S\u00e3o-Francisco-do-Gl\u00f3ria-est\u00e1-na-semifinal-de-Concurso-Nacional-do-MEC-e-FNDE-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/Merendeira-de-S\u00e3o-Francisco-do-Gl\u00f3ria-est\u00e1-na-semifinal-de-Concurso-Nacional-do-MEC-e-FNDE-300x225.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/Merendeira-de-S\u00e3o-Francisco-do-Gl\u00f3ria-est\u00e1-na-semifinal-de-Concurso-Nacional-do-MEC-e-FNDE.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>H\u00e1 quase 29 anos trabalhando como merendeira em S\u00e3o Francisco do Gl\u00f3ria, cidade localizada a 45 Km de Muria\u00e9, Elza do Carmo Paiva, conhecida carinhosamente como \u201cTia Elza\u201d, est\u00e1 na final do Concurso Nacional de Melhores Receitas da Alimenta\u00e7\u00e3o Escolar, promovido pelo Minist\u00e9rio da Educa\u00e7\u00e3o e Cultura (MEC) e do Fundo Nacional de Desenvolvimento Escolar (FNDE), concorrendo com a Lasanha Nutritiva de Fub\u00e1. Esta \u00e9 a primeira vez que participa de um concurso do tipo.<\/p>\n<p>O concurso visa valorizar o papel das merendeiras e promover a forma\u00e7\u00e3o de h\u00e1bitos saud\u00e1veis no ambiente escolar. No momento da inscri\u00e7\u00e3o, al\u00e9m da receita, tamb\u00e9m foi cadastrada uma a\u00e7\u00e3o de Educa\u00e7\u00e3o Alimentar e Nutricional denominada &#8220;Milho, o verdadeiro cereal radical&#8221;, vinculada \u00e0 receita elaborada, realizada por Naylara Adrielle, nutricionista respons\u00e1vel pela merenda da Escola Municipal Ant\u00f4nio Franco Laviola.<\/p>\n<p>Elza concorreu com mais de 1300 receitas na fase eliminat\u00f3ria, chegou \u00e0 etapa estadual concorrendo com mais de 200, na semifinal com 20 da regi\u00e3o sudeste e agora est\u00e1 entre as finalistas, que englobam 3 de cada regi\u00e3o do Brasil. Ao todo, ser\u00e3o 5 campe\u00e3s, uma por regi\u00e3o. Para ela, essa \u00e9 uma forma de valorizar seu trabalho e de todos os seus colegas, al\u00e9m de ser muito importante para o munic\u00edpio. \u201cFiquei muito satisfeita! \u00c9 uma honra participar de um concurso t\u00e3o importante. Gra\u00e7as \u00e0 Naylara, conseguimos chegar t\u00e3o longe. Sinto-me feliz e lisonjeada em representar toda comunidade, onde sou muito bem tratada e feliz pelo trabalho que fa\u00e7o\u201d, conta.<\/p>\n<p>A fase final do concurso ocorrer\u00e1 em Bras\u00edlia entre os dias 23 a 26 de outubro. Os vencedores receber\u00e3o um pr\u00eamio de R$ 6 mil e uma viagem internacional com acompanhante, al\u00e9m de um conjunto de manipuladores de alimentos, com touca e avental personalizados e um certificado de participa\u00e7\u00e3o. Tamb\u00e9m ter\u00e3o a oportunidade de participar de curso de capacita\u00e7\u00e3o em boas pr\u00e1ticas na alimenta\u00e7\u00e3o escolar.<\/p>\n<p>O secret\u00e1rio municipal de Educa\u00e7\u00e3o, L\u00e1zaro Luiz Lazaroni Freitas, recebeu a not\u00edcia do resultado parcial com muita satisfa\u00e7\u00e3o. &#8220;Chegar at\u00e9 a etapa final representa a qualidade e compet\u00eancia t\u00e9cnica de nossa equipe, representada por Dona Elza. O comprometimento e carinho ao preparar esta receita podem ser vistos no dia a dia, no ambiente escolar. A satisfa\u00e7\u00e3o de estarmos entre as melhores receitas nutritivas do Brasil, nos motiva a investir, cada vez mais, em nossos profissionais. Todos n\u00f3s da Administra\u00e7\u00e3o estamos muito esperan\u00e7osos em conseguir vencer mais uma etapa do concurso\u201d, disse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 quase 29 anos trabalhando como merendeira em S\u00e3o Francisco do Gl\u00f3ria, cidade localizada a 45 Km de Muria\u00e9, Elza do Carmo Paiva, conhecida carinhosamente como \u201cTia Elza\u201d, est\u00e1 na final do Concurso Nacional de Melhores Receitas da Alimenta\u00e7\u00e3o Escolar, promovido pelo Minist\u00e9rio da Educa\u00e7\u00e3o e Cultura (MEC) e do Fundo Nacional de Desenvolvimento Escolar &#8230; <a title=\"Merendeira de S\u00e3o Francisco do Gl\u00f3ria est\u00e1 na final de Concurso Nacional do MEC e FNDE\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/merendeira-de-sao-francisco-do-gloria-esta-na-final-de-concurso-nacional-do-mec-e-fnde\/\" aria-label=\"Read more about Merendeira de S\u00e3o Francisco do Gl\u00f3ria est\u00e1 na final de Concurso Nacional do MEC e FNDE\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":40857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[362,1143,1142,419,226],"class_list":["post-40852","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regiao","tag-brasil","tag-mec","tag-merendeira","tag-minas-gerais","tag-sao-francisco-do-gloria"],"acf":[],"aioseo_notices":[],"views":151,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/40852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=40852"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/40852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/40857"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=40852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=40852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=40852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}