{"id":40844,"date":"2017-09-21T18:24:12","date_gmt":"2017-09-21T21:24:12","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=40844"},"modified":"2017-09-21T18:24:12","modified_gmt":"2017-09-21T21:24:12","slug":"fe-e-fanatismo","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/fe-e-fanatismo\/","title":{"rendered":"F\u00e9 e fanatismo"},"content":{"rendered":"<p>Tudo aquilo em que exageramos \u00e9 prejudicial. A bebida em excesso, a comida em excesso, at\u00e9 a paix\u00e3o, se excessiva transmuda-se em obsess\u00e3o. Com a religi\u00e3o, n\u00e3o \u00e9 diferente.<\/p>\n<p>O fanatismo muitas vezes andou lado a lado com as mais diversas formas de express\u00e3o religiosa. A humanidade j\u00e1 assistiu a sacrif\u00edcios de animais e at\u00e9 de seres humanos em oferendas para acalmar vulc\u00f5es em erup\u00e7\u00e3o ou para agradar deuses; milhares de pessoas foram queimadas em pra\u00e7a p\u00fablica em nome de cren\u00e7as religiosas; mulheres continuam sendo escondidas atr\u00e1s de burcas negras, discriminadas e massacradas em seus anseios e homens se deixam explodir em bombas em nome de uma religi\u00e3o que se prendeu no tempo e n\u00e3o se abre para uma verdadeira concep\u00e7\u00e3o Deus, mais coerente com a racionalidade.<\/p>\n<p>A f\u00e9, embora se opondo a um racioc\u00ednio cartesiano, tem sido sim um grande esteio para o homem, em momentos de inseguran\u00e7a e fragilidade. Uma ora\u00e7\u00e3o, tem mais for\u00e7a pela motiva\u00e7\u00e3o subjetiva que provoca naquele que ora, do que por si mesma. Seu efeito \u00e9 mais imanente do que transcendente. Se pronunciada com a aten\u00e7\u00e3o interior daquele que ora, sem as distra\u00e7\u00f5es exteriores, produz efeitos positivos, chamados por muitos de milagre.<\/p>\n<p>Mas quando a f\u00e9 extrapola determinados limites ela atinge o terreno perigoso do fanatismo. O uso de cil\u00edcios, mortifica\u00e7\u00f5es, cintos com pregos para ferir o corpo como forma de conseguir, com o sofrimento, as gra\u00e7as do Criador ou de algum santo protetor, foi sempre muito recorrente nas religi\u00f5es, partindo-se do err\u00f4neo princ\u00edpio de que o sofrimento enobrece, quando na realidade degrada. E isso \u00e9 fazer pouco do pr\u00f3prio criador. No S\u00e9c. IV, Aur\u00e9lio Agostinho fazia coisas semelhantes, mas ele viveu no s\u00e9c. IV. J\u00e1 no S\u00e9c. XIII, por volta do ano 1250, Tom\u00e1s de Aquino j\u00e1 ensinava que devemos tratar bem o corpo, pois o corpo \u00e9 o templo de Deus.<\/p>\n<p>N\u00e3o \u00e9 dif\u00edcil entender determinados comportamentos em rela\u00e7\u00e3o a cren\u00e7as religiosas nos prim\u00f3rdios das civiliza\u00e7\u00f5es ou em grupos \u00e9tnicos que se prenderam a cren\u00e7as do passado e continuam exercitando tais pr\u00e1ticas. \u00c9 o caso de determinadas \u201ccorrentes\u201d que recebemos em nossas caixas de correio. Corrente \u00e9 o nome exemplarmente adequado, pois algumas pessoas se encontram mesmo acorrentadas a esses conceitos.<\/p>\n<p>A \u00faltima que recebi foi a \u201cCorrente Milagrosa de Nossa Senhora Aparecida\u201d. Diz o texto que aquele que n\u00e3o mandar quatro c\u00f3pias di\u00e1rias a diferentes pessoas, durante sessenta dias poder\u00e1 sofrer graves conseq\u00fc\u00eancias. Afirma ainda o texto que o dono de um escrit\u00f3rio precisava de 1 milh\u00e3o de reais e o ganhou, mas como interrompeu a corrente&#8230; teve v\u00e1rios problemas. O dono de uma padaria interrompeu a corrente e perdeu o seu filho. Com todo o respeito \u00e0s convic\u00e7\u00f5es alheias, acho dif\u00edcil acreditar que a bondosa Nossa Senhora Aparecida possa ter um temperamento assim, t\u00e3o vingativo.<\/p>\n<p>Eu nunca gostei de correntes. Nem as que me prendem o esp\u00edrito e nem essas que circulam pelas caixas de correio. Principalmente quando v\u00eam acompanhadas de pragas para quem interromp\u00ea-las.<\/p>\n<p>Ningu\u00e9m sabe como \u00e9 o Criador ou o ordenador desse imenso e maravilhoso Universo. \u00a0Nem as Filosofias e nem as Igrejas. Mas temos a suposi\u00e7\u00e3o de que um ser dotado de uma perfei\u00e7\u00e3o t\u00e3o imensa assim, capaz de criar ou ordenar o Universo, deve passar bem longe dos fanatismos e dos radicalismos praticados pelos seres humanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tudo aquilo em que exageramos \u00e9 prejudicial. A bebida em excesso, a comida em excesso, at\u00e9 a paix\u00e3o, se excessiva transmuda-se em obsess\u00e3o. Com a religi\u00e3o, n\u00e3o \u00e9 diferente. O fanatismo muitas vezes andou lado a lado com as mais diversas formas de express\u00e3o religiosa. A humanidade j\u00e1 assistiu a sacrif\u00edcios de animais e at\u00e9 &#8230; <a title=\"F\u00e9 e fanatismo\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/fe-e-fanatismo\/\" aria-label=\"Read more about F\u00e9 e fanatismo\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31,36],"tags":[329,901,1141,1140,74],"class_list":["post-40844","post","type-post","status-publish","format-standard","hentry","category-colunistas","category-logos-adellunar-marge","tag-adellunar-marge","tag-colunistas","tag-fanatismo","tag-fe","tag-muriae"],"acf":[],"aioseo_notices":[],"views":294,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/40844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=40844"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/40844\/revisions"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=40844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=40844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=40844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}