{"id":40305,"date":"2017-09-05T19:21:36","date_gmt":"2017-09-05T22:21:36","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=40305"},"modified":"2017-09-05T19:32:05","modified_gmt":"2017-09-05T22:32:05","slug":"pm-apreende-buchas-barras-e-pes-de-maconha-no-bairro-safira","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/pm-apreende-buchas-barras-e-pes-de-maconha-no-bairro-safira\/","title":{"rendered":"PM apreende buchas, barras e p\u00e9s de maconha no Bairro Safira"},"content":{"rendered":"<figure id=\"attachment_40306\" aria-describedby=\"caption-attachment-40306\" style=\"width: 290px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/CAPA.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-40306\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/CAPA-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/CAPA-300x225.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/09\/CAPA.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-40306\" class=\"wp-caption-text\">Cr\u00e9ditos: ASCOM PMMG<\/figcaption><\/figure>\n<p>Durante patrulhamento, na manh\u00e3 de segunda-feira (4), militares avistaram um cidad\u00e3o, de 19 anos, pr\u00f3ximo a um local conhecido no meio policial pela venda de entorpecentes. Ao se aproximarem do suspeito para a abordagem, o jovem se escondeu em uma casa onde foram encontrados, no quintal, dois p\u00e9s de maconha e, em seu bolso, havia uma bucha da erva.<\/p>\n<p>Durante as buscas, com o aux\u00edlio da cadela Iza, foram localizados dentro de um t\u00eanis, no quarto do autor, mais dez tabletes da mesma droga e R$70 em dinheiro. No fundo da geladeira, foi encontrado mais um tablete maior de maconha.<\/p>\n<p>Ainda pelo local, com apoio das demais viaturas, foi abordado no mesmo bairro, um homem de 32 anos, j\u00e1 conhecido no meio policial que, ap\u00f3s consulta no sistema informatizado, foi constatado um mandado de pris\u00e3o em aberto.<\/p>\n<p>Os autores foram presos e conduzidos para a delegacia com os materiais apreendidos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante patrulhamento, na manh\u00e3 de segunda-feira (4), militares avistaram um cidad\u00e3o, de 19 anos, pr\u00f3ximo a um local conhecido no meio policial pela venda de entorpecentes. Ao se aproximarem do suspeito para a abordagem, o jovem se escondeu em uma casa onde foram encontrados, no quintal, dois p\u00e9s de maconha e, em seu bolso, havia &#8230; <a title=\"PM apreende buchas, barras e p\u00e9s de maconha no Bairro Safira\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/pm-apreende-buchas-barras-e-pes-de-maconha-no-bairro-safira\/\" aria-label=\"Read more about PM apreende buchas, barras e p\u00e9s de maconha no Bairro Safira\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":40306,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30],"tags":[671,74,93,138,3,1062],"class_list":["post-40305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-muriae","tag-maconha","tag-muriae","tag-policia-militar","tag-seguranca","tag-slide","tag-trafico"],"acf":[],"aioseo_notices":[],"views":117,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/40305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=40305"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/40305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/40306"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=40305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=40305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=40305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}