{"id":40047,"date":"2017-08-31T20:08:33","date_gmt":"2017-08-31T23:08:33","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=40047"},"modified":"2017-09-01T09:56:43","modified_gmt":"2017-09-01T12:56:43","slug":"a-banalizacao-da-vida","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/a-banalizacao-da-vida\/","title":{"rendered":"A banaliza\u00e7\u00e3o da vida"},"content":{"rendered":"<p>Hoje come\u00e7o esta coluna com uma tristeza imensa no cora\u00e7\u00e3o. A morte da competente m\u00e9dica veterin\u00e1ria, Manoela da Matta, v\u00edtima de um latroc\u00ednio covarde, infame, praticado por dois adolescentes, um de 15 e outro de 17 anos, chocou a sociedade muriaeense. Amiga e parceira de todos os amantes da cria\u00e7\u00e3o de cavalos, especialmente do Mangalarga Marchador, Manoela fazia da sua profiss\u00e3o uma incr\u00edvel forma de colecionar amigos.<\/p>\n<p>O crime b\u00e1rbaro ocorrido \u00e0s 15 horas, nesta quarta feira, em plena Rua S\u00e3o Pedro, no centro da cidade, numa das ruas mais disputadas para se morar e por causa de um m\u00edsero celular, mostra o retrato aterrorizador da seguran\u00e7a p\u00fablica do pa\u00eds e traz \u00e0 discuss\u00e3o, mais uma vez, a quest\u00e3o da criminalidade juvenil.<\/p>\n<p>A primeira constata\u00e7\u00e3o \u00e9 de que h\u00e1 de se tomar medidas inadi\u00e1veis para conter a a\u00e7\u00e3o desses jovens bandidos que se proliferam como insetos no meio das drogas, as quais s\u00e3o manipuladas em plena luz do dia, nos recantos ou nas pra\u00e7as principais das cidades. \u00c9 a impunidade gerada por uma legisla\u00e7\u00e3o paternalista, denominada Estatuto da Crian\u00e7a e do Adolescente (ECA).<\/p>\n<p>O Estatuto, j\u00e1 ultrapassado, n\u00e3o atende \u00e0s necessidades da realidade atual. Trata-se de um verdadeiro escudo de prote\u00e7\u00e3o para jovens infratores. A lei estabelece um crit\u00e9rio et\u00e1rio, onde um indiv\u00edduo que tem a idade, por exemplo, de 17 anos, 11 meses e 29 dias, ao cometer um assassinato ou qualquer ato delituoso, mesmo que seja um crime considerado hediondo e executado com alto grau de perversidade, n\u00e3o \u00e9 considerado um criminoso. Ele \u00e9 considerado, t\u00e3o somente, praticante de um \u201cato infracional\u201d, cuja puni\u00e7\u00e3o \u00e9 a interna\u00e7\u00e3o em uma unidade socioeducativa por um tempo m\u00e1ximo de tr\u00eas anos. Se, por um acaso, esse menor cometer v\u00e1rios crimes, ainda que seja em s\u00e9rie, nenhum minuto ser\u00e1 acrescentado a esse tempo de interna\u00e7\u00e3o. A quest\u00e3o da redu\u00e7\u00e3o da maioridade penal \u00e9 bastante pol\u00eamica, mas h\u00e1 de se considerar que os crimes b\u00e1rbaros continuam acontecendo e que o sentimento de indigna\u00e7\u00e3o da sociedade \u00e9 muito grande, o que exige uma tomada de posi\u00e7\u00e3o imediata das autoridades no sentido de se encontrar uma solu\u00e7\u00e3o vi\u00e1vel.<\/p>\n<p>N\u00f3s sabemos que n\u00e3o h\u00e1 uma solu\u00e7\u00e3o m\u00e1gica para se conter a criminalidade juvenil. Mas, uma coisa \u00e9 certa: qualquer indiv\u00edduo com idade superior a l6 anos, tendo ao seu dispor a quantidade de informa\u00e7\u00f5es que o mundo globalizado lhe oferece, e, com as tecnologias dispon\u00edveis que s\u00e3o acessadas por todos eles com incr\u00edvel facilidade, n\u00e3o h\u00e1 como negar que todos que constituem a faixa et\u00e1ria entre 16 e 18 anos, exceto em casos especial\u00edssimos, t\u00eam hoje, a absoluta consci\u00eancia do que \u00e9 um ato l\u00edcito ou il\u00edcito. Portanto, eles podem, perfeitamente, serem punidos de forma exemplar como forma de inibir e reduzir a criminalidade hoje reinante no pa\u00eds.<\/p>\n<p>Enquanto n\u00e3o se toma as provid\u00eancias necess\u00e1rias para mudar este estado de coisas, pessoas da sociedade como a querida Manoela v\u00e3o pagando a conta com a pr\u00f3pria vida, como se ela, a vida, n\u00e3o fosse o bem mais precioso que o homem tem. Infelizmente!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje come\u00e7o esta coluna com uma tristeza imensa no cora\u00e7\u00e3o. A morte da competente m\u00e9dica veterin\u00e1ria, Manoela da Matta, v\u00edtima de um latroc\u00ednio covarde, infame, praticado por dois adolescentes, um de 15 e outro de 17 anos, chocou a sociedade muriaeense. Amiga e parceira de todos os amantes da cria\u00e7\u00e3o de cavalos, especialmente do Mangalarga &#8230; <a title=\"A banaliza\u00e7\u00e3o da vida\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/a-banalizacao-da-vida\/\" aria-label=\"Read more about A banaliza\u00e7\u00e3o da vida\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31,1,33],"tags":[1046,901,331,74],"class_list":["post-40047","post","type-post","status-publish","format-standard","hentry","category-colunistas","category-gerais","category-politica-e-atualidades-francisco-laviola","tag-banalizacao-da-vida","tag-colunistas","tag-francisco-laviola","tag-muriae"],"acf":[],"aioseo_notices":[],"views":88,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/40047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=40047"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/40047\/revisions"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=40047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=40047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=40047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}