{"id":39958,"date":"2017-08-31T19:46:29","date_gmt":"2017-08-31T22:46:29","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=39958"},"modified":"2017-08-31T19:46:29","modified_gmt":"2017-08-31T22:46:29","slug":"renzo-braz-se-reune-com-presidente-do-sindicato-rural-de-muriae","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/renzo-braz-se-reune-com-presidente-do-sindicato-rural-de-muriae\/","title":{"rendered":"Renzo Braz se re\u00fane com presidente do Sindicato Rural de Muria\u00e9"},"content":{"rendered":"<p><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/Renzo-Braz-se-re\u00fane-com-presidente-do-Sindicato-Rural-de-Muria\u00e9.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-39987 alignleft\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/Renzo-Braz-se-re\u00fane-com-presidente-do-Sindicato-Rural-de-Muria\u00e9-300x201.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/Renzo-Braz-se-re\u00fane-com-presidente-do-Sindicato-Rural-de-Muria\u00e9-300x201.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/Renzo-Braz-se-re\u00fane-com-presidente-do-Sindicato-Rural-de-Muria\u00e9.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Renzo Braz recebeu em seu gabinete, na sexta-feira (25), o presidente do Sindicato de Produtores Rurais de Muria\u00e9, Henrique Aquino.<\/p>\n<p>O presidente convidou o deputado para participar de um encontro que aconteceu no dia (30), no Parque de Exposi\u00e7\u00f5es de Muria\u00e9, entre produtores rurais de toda regi\u00e3o, para debater o baixo pre\u00e7o do leite, ocasionado pela redu\u00e7\u00e3o do consumo e o aumento da importa\u00e7\u00e3o do alimento.<\/p>\n<p>Estiveram no evento, o presidente da Comiss\u00e3o T\u00e9cnica de Pecu\u00e1ria de Leite da Federa\u00e7\u00e3o da Agricultura e Pecu\u00e1ria do Estado de Minas Gerais (FAEMG), Eduardo de Carvalho Pena e o presidente da Associa\u00e7\u00e3o Brasileira dos Produtores de Leite (Abraleite), Geraldo Borges.<\/p>\n<p>O objetivo do evento foi discutir sugest\u00f5es e solu\u00e7\u00f5es para o problema apresentado e redigir um documento com apoio de todos os presentes, para ser encaminhado para os \u00f3rg\u00e3os competentes em Bras\u00edlia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Renzo Braz recebeu em seu gabinete, na sexta-feira (25), o presidente do Sindicato de Produtores Rurais de Muria\u00e9, Henrique Aquino. O presidente convidou o deputado para participar de um encontro que aconteceu no dia (30), no Parque de Exposi\u00e7\u00f5es de Muria\u00e9, entre produtores rurais de toda regi\u00e3o, para debater o baixo pre\u00e7o do leite, ocasionado &#8230; <a title=\"Renzo Braz se re\u00fane com presidente do Sindicato Rural de Muria\u00e9\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/renzo-braz-se-reune-com-presidente-do-sindicato-rural-de-muriae\/\" aria-label=\"Read more about Renzo Braz se re\u00fane com presidente do Sindicato Rural de Muria\u00e9\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":39987,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30],"tags":[910,527,74,731,1042,969],"class_list":["post-39958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-muriae","tag-economia","tag-leite","tag-muriae","tag-renzo-braz","tag-reuniao","tag-sindicato-rural"],"acf":[],"aioseo_notices":[],"views":144,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/39958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=39958"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/39958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/39987"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=39958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=39958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=39958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}