{"id":39626,"date":"2017-08-25T16:00:33","date_gmt":"2017-08-25T19:00:33","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=39626"},"modified":"2017-08-24T22:48:53","modified_gmt":"2017-08-25T01:48:53","slug":"lions-recebe-a-visita-do-governador-do-distrito-lc12","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/lions-recebe-a-visita-do-governador-do-distrito-lc12\/","title":{"rendered":"Lions recebe a visita do Governador do Distrito LC12"},"content":{"rendered":"<p><a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/2.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-medium wp-image-39627\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/2-300x225.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/2.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0183.jpg\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-39628\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0183-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0183-300x200.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0183-290x192.jpg 290w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0183.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0188.jpg\"><img decoding=\"async\" class=\"alignleft size-medium wp-image-39629\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0188-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0188-300x200.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0188-290x192.jpg 290w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0188.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0972.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-39631\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0972-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0972-300x200.jpg 300w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0972-290x192.jpg 290w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2017\/08\/DSC_0972.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>Os membros dos Lions do Centro, da Barra e do Muria\u00e9 Helen Keller, receberam, na segunda-feira (21), o casal governador Jo\u00e3o Paulo Lima Teixeira e Aline Lima, do distrito LC12, do qual fazem parte os tr\u00eas clubes. Durante o dia, o governador Jo\u00e3o Paulo conheceu um pouco do trabalho desenvolvido na cidade e visitou o Hospital S\u00e3o Paulo. Durante a noite, foi realizado uma assembleia festiva, no restaurante Serra do Sol, para recepcionar o governador do distrito, estando presente tamb\u00e9m o Lions Clube Mira\u00ed.<\/p>\n<p>Os tr\u00eas clubes unem for\u00e7as para trabalhar ainda mais juntos em favor daqueles que precisam. Este foi um dos assuntos tocados pelo governador durante a sua visita.<\/p>\n<p>M\u00f4nica Thompson, presidente do Lions Clube Muria\u00e9 Barra, disse que a visita do governador j\u00e1 era esperada pelos tr\u00eas clubes de Muria\u00e9. \u201cN\u00f3s planej\u00e1vamos este encontro com o governador h\u00e1 algum tempo. Os tr\u00eas Lions trabalharam juntos para que fosse poss\u00edvel passar seus ensinamentos para cada clube. Reunimo-nos em um proveitoso bate-papo com o governador, que \u00e9 bem objetivo. Apesar da pouca idade, ele possui muita bagagem\u201d, disse.<\/p>\n<p>M\u00f4nica conta que o governador Jo\u00e3o Paulo apresentou novas campanhas mensais em que devem ser aplicadas metas para todos os Lions. \u201cEste m\u00eas, por exemplo, o Lions Barra realizou uma campanha ambiental na Usina da Fuma\u00e7a. Fora isso, realizaremos uma campanha sobre civismo nas escolas. J\u00e1 estamos planejando tudo para que tamb\u00e9m seja um sucesso\u201d, contou<\/p>\n<p>Wanderly Torres, presidente do Lions Clube Muria\u00e9 Helen Keller, que, recentemente promoveu a tradicional \u201cGalinhada do Lions\u201d, em prol do 4\u00ba andar da enfermaria do Hospital S\u00e3o Paulo, falou sobre a visita do governador e de sua esposa Aline. \u201cFoi um prazer receber este jovem, que, aos 35 anos, assumiu a governadoria do Lions. Sabemos que a responsabilidade \u00e9 imensa, mas ele passou, nitidamente, para todos n\u00f3s o verdadeiro sentido do leonismo: o amor e companheirismo nas atitudes. Hoje tivemos nossos conceitos sobre leonismo reafirmados\u201d, contou.<\/p>\n<p>Wanderly disse tamb\u00e9m que ficou emocionada com a mensagem passada pela esposa do governador, a companheira Aline. \u201c\u00a0 Nossa companheira fez uma coloca\u00e7\u00e3o muito bonita sobre o amor. Ela disse que servir \u00e9 o amor em movimento. Acredito que esta atitude coloca, cada um de n\u00f3s, em um patamar bem avan\u00e7ado porque n\u00f3s temos o prazer de servir, com muito amor, aos nossos necessitados. Se todos n\u00f3s cooperarmos, em breve teremos uma comunidade bem melhor com metas de inovar, motivar e servir. Isso \u00e9 ser Lions\u201d<\/p>\n<p>De acordo com Wanderly, o governador visitou as depend\u00eancias do Hospital S\u00e3o Paulo, onde foi poss\u00edvel perceber um pouco do trabalho que o Lions realiza no local. \u201cL\u00e1 pudemos perceber a alegria que o governador teve ao ver nossos esfor\u00e7os. Foi gratificante\u201d, disse.<\/p>\n<p>O presidente do Lions Clube Muria\u00e9 Centro, Geraldo Majela Queiroz Botelho, esteve presente na confraterniza\u00e7\u00e3o falando a respeito tamb\u00e9m da visita do governador ao Hospital S\u00e3o Paulo. \u201cAntes de visitar o hospital, o governador se reuniu com os dirigentes de cada clube na parte da manh\u00e3. Durante a tarde, fomos todos para o Hospital S\u00e3o Paulo onde ele p\u00f4de conhecer melhor o trabalho que realizamos na institui\u00e7\u00e3o\u201d, contou.<\/p>\n<p>De acordo com Majela, o trabalho desenvolvido pelo Lions Clube Muria\u00e9 Centro, no Hospital S\u00e3o Paulo, funciona no setor de hemodi\u00e1lise. Na segunda-feira foram doadas quatro cadeiras de rodas e, na ter\u00e7a-feira (22), foram doadas mais seis.<\/p>\n<p>Na oportunidade o governador Jo\u00e3o Paulo Lima Teixeira anunciou que tudo far\u00e1 para destinar uma verba do Lions Internacional ao Hospital S\u00e3o Paulo, a fim de atender as necessidades da enfermaria e da hemodi\u00e1lise, ambas atendidas pelo SUS.<\/p>\n<p>Na solenidade, foram entregues aos presentes, mudas de palmeiras Phoenix seguindo a orienta\u00e7\u00e3o do governador Jo\u00e3o Paulo. A cada m\u00eas, ser\u00e1 abordado pelos Lions, um tema diferente. O m\u00eas de agosto ser\u00e1 sobre preserva\u00e7\u00e3o ambiental.<\/p>\n<p><strong>Sobre o governador do Lions &#8211;<\/strong> Jo\u00e3o Paulo Lima Teixeira faz parte do Lions Clube h\u00e1 10 anos e est\u00e1 como governador h\u00e1 apenas tr\u00eas meses. O mandato \u00e9 de um ano. Em entrevista, o governador falou a respeito dos tr\u00eas Lions de Muria\u00e9. \u201cN\u00f3s levamos daqui uma bonita experi\u00eancia de trabalho. Cada clube na sua \u00e1rea, no seu foco. S\u00e3o os clubes que mais trabalham, estamos levando uma boa impress\u00e3o dos clubes e dos associados. Todos est\u00e3o levando a s\u00e9rio a quest\u00e3o de servir e fazer o bem ao pr\u00f3ximo\u201d, contou.<\/p>\n<p><img decoding=\"async\" class=\"ngg_displayed_gallery mceItem\" src=\"https:\/\/anoticiaonline.com.br\/site\/nextgen-attach_to_post\/preview\/id--39712\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os membros dos Lions do Centro, da Barra e do Muria\u00e9 Helen Keller, receberam, na segunda-feira (21), o casal governador Jo\u00e3o Paulo Lima Teixeira e Aline Lima, do distrito LC12, do qual fazem parte os tr\u00eas clubes. Durante o dia, o governador Jo\u00e3o Paulo conheceu um pouco do trabalho desenvolvido na cidade e visitou o &#8230; <a title=\"Lions recebe a visita do Governador do Distrito LC12\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/lions-recebe-a-visita-do-governador-do-distrito-lc12\/\" aria-label=\"Read more about Lions recebe a visita do Governador do Distrito LC12\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":39631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[1022,1023,1021,182,1020,1019,1018,3],"class_list":["post-39626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gerais","tag-aline-lima","tag-distrito-lc12","tag-governador-joao-paulo-lima-teixeira","tag-lions","tag-lions-clube-muriae-barra","tag-lions-clube-muriae-centro","tag-lions-clube-muriae-helen-keller","tag-slide"],"acf":[],"aioseo_notices":[],"views":156,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/39626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=39626"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/39626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/39631"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=39626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=39626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=39626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}