{"id":38913,"date":"2017-08-24T18:00:20","date_gmt":"2017-08-24T21:00:20","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=38913"},"modified":"2017-08-24T18:00:20","modified_gmt":"2017-08-24T21:00:20","slug":"engana-que-eu-detesto","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/engana-que-eu-detesto\/","title":{"rendered":"Engana que eu detesto"},"content":{"rendered":"<p>Na \u00faltima semana, escrevi aqui neste espa\u00e7o sobre a fragmenta\u00e7\u00e3o partid\u00e1ria existente no pa\u00eds e a desmoraliza\u00e7\u00e3o dos partidos como quadros de representa\u00e7\u00e3o pol\u00edtica. N\u00e3o h\u00e1 d\u00favidas de que o atual modelo de representa\u00e7\u00e3o j\u00e1 foi para o ralo, devido ao fluxo de propinas, uso de caixa dois e a enxurrada de dela\u00e7\u00f5es de pol\u00edticos e empres\u00e1rios que se encontram presos, ap\u00f3s as a\u00e7\u00f5es da Policia Federal e do Minist\u00e9rio P\u00fablico. Grande parte do eleitorado que re\u00fane condi\u00e7\u00f5es de opinar j\u00e1 n\u00e3o se identifica mais com quase nenhum dos atuais partidos.\u00a0 Sobra, talvez, t\u00e3o somente os radicais petistas, que, fa\u00e7a chuva ou fa\u00e7a sol, subindo ou descendo a ladeira, obedecem cegamente essa verdadeira \u201cseita\u201d comandada por Lula.<\/p>\n<p>A doutrina pol\u00edtica maquiav\u00e9lica implementada por deputados e senadores da Rep\u00fablica n\u00e3o tem limites. Na medida em que os \u00f3rg\u00e3os de investiga\u00e7\u00e3o v\u00e3o derrubando barreiras e dificultando a elegibilidade dos atuais pol\u00edticos, eles v\u00e3o se mexendo e usando de subterf\u00fagios e trapa\u00e7as para viabilizarem as suas elei\u00e7\u00f5es. Querem exemplos? Se n\u00e3o bastasse o fundo partid\u00e1rio triplicado pelo governo Dilma para financiar partidos e pol\u00edticos, queriam os parlamentares, apesar da crise, criar um fundo para financiar as pr\u00f3ximas elei\u00e7\u00f5es, que atingiria a assombrosa quantia de R$ 3,6 bilh\u00f5es, recursos do Tesouro Nacional, ou seja, dinheiro tirado do bolso do contribuinte. Com a proibi\u00e7\u00e3o do financiamento de campanha de empresas determinado pelo STF, eles estavam tentando criar esse \u201cfund\u00e3o\u201d absurdo, a ser pago pelo povo brasileiro. Um nome at\u00e9 pomposo: Fundo de Financiamento da Democracia. Por enquanto, esse fundo n\u00e3o sair\u00e1, uma vez que as elei\u00e7\u00f5es j\u00e1 est\u00e3o pr\u00f3ximas e o receio de uma rea\u00e7\u00e3o contr\u00e1ria do povo fez com que deixassem para a Comiss\u00e3o do Or\u00e7amento a tarefa de fixar o valor dessa artimanha. Querem outro exemplo? Como a maioria dos partidos, seja por causa de falta de ideologia pr\u00f3pria e programas compat\u00edveis, ou seja por causa das trapa\u00e7as engendradas nos \u00faltimos anos, e descobertas, os seus dirigentes est\u00e3o apostando agora na mudan\u00e7a dos nomes das agremia\u00e7\u00f5es partid\u00e1rias. Assim, as famosas \u201csopas\u201d de letrinhas est\u00e3o saindo de cena e come\u00e7am a usar nomes que visam, n\u00e3o a forma\u00e7\u00e3o de um partido, mas a sugest\u00e3o de um movimento. Por exemplo: o PTN, virou \u201cPodemos\u201d; o PSDC, est\u00e1 se intitulando \u201cDemocracia Crist\u00e3\u201d; o PMDB, um dos mais hist\u00f3ricos, at\u00e9 pelas suas trapa\u00e7as, quer voltar a ser apenas MDB; o PEN, quer passar a ser \u201cPatriota\u201d; o DEM, est\u00e1 estudando a possibilidade de se chamar \u201cMUDE\u201d; O PSL, se metamorfoseou como \u201cLivres\u201d; e o PT do B, j\u00e1 virou \u201cAvante\u201d. A\u00ed est\u00e1, amigos, mais uma jogada de marketing para enganar o eleitor. Mudam-se os excrementos s\u00f3lidos, mas as moscas continuam as mesmas.<\/p>\n<p>E a reforma pol\u00edtica que est\u00e3o fazendo a toque de caixa? Ser\u00e1 que v\u00e3o continuar as coliga\u00e7\u00f5es esp\u00farias, os conchavos e as m\u00e1s influ\u00eancias na hora da elei\u00e7\u00e3o? O senador sem voto, vai continuar? Algumas propostas de altera\u00e7\u00e3o est\u00e3o sendo aprovadas na Comiss\u00e3o especial de reforma. Mas ser\u00e1 que passar\u00e3o pela aprova\u00e7\u00e3o no Plen\u00e1rio da C\u00e2mara de Deputados e do Senado? \u00c9 ver para crer.<\/p>\n<p>Pelo menos uma coisa \u00e9 certa: n\u00e3o podemos deixar que nos enganem com qualquer tipo de maquiagem, principalmente se for atrav\u00e9s de uma reforma pol\u00edtica que n\u00e3o atenda \u00e0 democracia. H\u00e1 um dito popular ir\u00f4nico que diz: \u201cMe engana que eu gosto\u201d. Indigne-se. Seja um elemento ativo e ajude a lapidar a nossa democracia. \u00a0\u201cMude o sentido do ditado popular que, ao inv\u00e9s de ser ir\u00f4nico passa a ser real. Diga para eles: engana que eu detesto. A elei\u00e7\u00e3o de 2018 j\u00e1 est\u00e1 sendo preparada e cabe a n\u00f3s, eleitores, dizer atrav\u00e9s das urnas o que queremos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima semana, escrevi aqui neste espa\u00e7o sobre a fragmenta\u00e7\u00e3o partid\u00e1ria existente no pa\u00eds e a desmoraliza\u00e7\u00e3o dos partidos como quadros de representa\u00e7\u00e3o pol\u00edtica. N\u00e3o h\u00e1 d\u00favidas de que o atual modelo de representa\u00e7\u00e3o j\u00e1 foi para o ralo, devido ao fluxo de propinas, uso de caixa dois e a enxurrada de dela\u00e7\u00f5es de pol\u00edticos &#8230; <a title=\"Engana que eu detesto\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/engana-que-eu-detesto\/\" aria-label=\"Read more about Engana que eu detesto\">Ler mais<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[31,33],"tags":[901,966,74,352,967],"class_list":["post-38913","post","type-post","status-publish","format-standard","hentry","category-colunistas","category-politica-e-atualidades-francisco-laviola","tag-colunistas","tag-eleicoes","tag-muriae","tag-politica","tag-voto"],"acf":[],"aioseo_notices":[],"views":125,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/38913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=38913"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/38913\/revisions"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=38913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=38913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=38913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}