{"id":145201,"date":"2026-05-13T14:24:09","date_gmt":"2026-05-13T17:24:09","guid":{"rendered":"https:\/\/anoticiaonline.com.br\/site\/?p=145201"},"modified":"2026-05-13T14:24:09","modified_gmt":"2026-05-13T17:24:09","slug":"tarifa-social-e-desconto-social-cerca-de-52-mil-familias-em-minas-ainda-podem-receber-desconto-na-conta-de-luz","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/tarifa-social-e-desconto-social-cerca-de-52-mil-familias-em-minas-ainda-podem-receber-desconto-na-conta-de-luz\/","title":{"rendered":"Tarifa Social e Desconto Social: cerca de 52 mil fam\u00edlias em Minas ainda podem receber desconto na conta de luz"},"content":{"rendered":"<p style=\"font-weight: 400;\">A Tarifa Social e o Desconto Social de Energia El\u00e9trica s\u00e3o\u00a0programas do Governo Federal\u00a0que ajudam fam\u00edlias de baixa renda a pagar menos na conta de luz. Em Minas Gerais, cerca de 52 mil clientes da Energisa Minas Rio poderiam receber um desses benef\u00edcios, mas ainda n\u00e3o t\u00eam acesso aos descontos, principalmente por falta de atualiza\u00e7\u00e3o dos dados no Cadastro \u00danico (Cad\u00danico) ou junto \u00e0 distribuidora.<\/p>\n<p style=\"font-weight: 400;\">Mesmo tendo direito ao benef\u00edcio, muitas fam\u00edlias deixam de receber o desconto porque os dados est\u00e3o desatualizados. Isso ocorre, principalmente, quando o nome da pessoa cadastrada no\u00a0Cad\u00danico\u00a0n\u00e3o \u00e9 o mesmo que consta como titular da conta de energia. Para que o desconto seja aplicado, a fatura precisa estar em nome da mesma pessoa registrada no\u00a0Cad\u00danico. Quando as informa\u00e7\u00f5es est\u00e3o corretas, o benef\u00edcio \u00e9 concedido automaticamente, sem necessidade de solicita\u00e7\u00e3o \u00e0 distribuidora.\u00a0Por isso, manter os dados atualizados \u00e9 essencial para garantir o recebimento do benef\u00edcio.<\/p>\n<p style=\"font-weight: 400;\">Segundo Jana\u00edna Lacerda, gerente de Servi\u00e7os Comerciais da distribuidora, a Energisa trabalha para tornar esse processo mais f\u00e1cil, e incentiva os clientes a manterem o cadastro em dia.<\/p>\n<p style=\"font-weight: 400;\">\u201cA Energisa disponibiliza canais digitais que funcionam 24 horas por dia, sete dias por semana, permitindo que o cliente realize servi\u00e7os como a mudan\u00e7a de titularidade da conta e a atualiza\u00e7\u00e3o de dados de forma simples e r\u00e1pida, sem sair de casa. J\u00e1 a atualiza\u00e7\u00e3o das informa\u00e7\u00f5es no\u00a0Cad\u00danico\u00a0deve ser feita no Centro de Refer\u00eancia de Assist\u00eancia Social (CRAS) mais pr\u00f3ximo\u201d, explica.<\/p>\n<p style=\"font-weight: 400;\"><strong>Tarifa Social<\/strong><\/p>\n<p style=\"font-weight: 400;\">A Tarifa Social de Energia El\u00e9trica garante 100% de desconto no consumo mensal de at\u00e9 80 kWh para fam\u00edlias que atendem aos crit\u00e9rios do programa. O consumo que ultrapassar esse limite \u00e9 cobrado sem desconto. O benef\u00edcio \u00e9 destinado a fam\u00edlias inscritas no\u00a0Cad\u00danico\u00a0com renda mensal por pessoa de at\u00e9 meio sal\u00e1rio-m\u00ednimo, a idosos a partir de 65 anos ou pessoas com defici\u00eancia que recebem o Benef\u00edcio de Presta\u00e7\u00e3o Continuada (BPC), al\u00e9m de fam\u00edlias inscritas no\u00a0Cad\u00danico\u00a0com renda total de at\u00e9 tr\u00eas sal\u00e1rios-m\u00ednimos que possuam integrantes que dependem do uso cont\u00ednuo de equipamentos el\u00e9tricos para tratamento de sa\u00fade. Quando o consumo fica dentro dos 80 kWh, a fam\u00edlia paga apenas taxas e tributos que n\u00e3o est\u00e3o diretamente ligados ao consumo de energia.<\/p>\n<p style=\"font-weight: 400;\"><strong>Desconto Social<\/strong><\/p>\n<p style=\"font-weight: 400;\">J\u00e1 o Desconto Social \u00e9 outro benef\u00edcio voltado \u00e0s fam\u00edlias de baixa renda. Ele pode reduzir o valor da conta de luz em 17,72% para clientes atendidos pela Energisa que tenham consumo mensal de at\u00e9 120 kWh.\u00a0O programa\u00a0\u00e9 destinado a fam\u00edlias inscritas no\u00a0Cad\u00danico, com renda mensal por pessoa entre meio e um sal\u00e1rio-m\u00ednimo.<strong>\u00a0<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>Atualize o cadastro na Energisa\u00a0pelos canais digitais:\u00a0<\/strong><\/p>\n<ul style=\"font-weight: 400;\">\n<li>Aplicativo Energisa\u00a0On:\u00a0<a href=\"http:\/\/energisa.com.br\/energisaon\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/energisa.com.br\/energisaon&amp;source=gmail&amp;ust=1778762705191000&amp;usg=AOvVaw3YZk_zDSjQ5A3Z47Z3ezVE\">energisa.com.br\/energisaon<\/a><\/li>\n<\/ul>\n<ul style=\"font-weight: 400;\">\n<li>Gisa:\u00a0<a href=\"http:\/\/energisa.com.br\/gisa\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/energisa.com.br\/gisa&amp;source=gmail&amp;ust=1778762705191000&amp;usg=AOvVaw0mj_K_3wlZ7u6mbXJXA0FI\">energisa.com.br\/gisa<\/a><\/li>\n<\/ul>\n<ul style=\"font-weight: 400;\">\n<li>Ag\u00eancia digital:\u00a0<a href=\"http:\/\/energisa.com.br\/servicos\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/energisa.com.br\/servicos&amp;source=gmail&amp;ust=1778762705191000&amp;usg=AOvVaw2ZjIVeDktDomFwZNVEqk65\">energisa.com.br\/servicos<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A Tarifa Social e o Desconto Social de Energia El\u00e9trica s\u00e3o\u00a0programas do Governo Federal\u00a0que ajudam fam\u00edlias de baixa renda a pagar menos na conta de luz. Em Minas Gerais, cerca de 52 mil clientes da Energisa Minas Rio poderiam receber um desses benef\u00edcios, mas ainda n\u00e3o t\u00eam acesso aos descontos, principalmente por falta de atualiza\u00e7\u00e3o &#8230; <a title=\"Tarifa Social e Desconto Social: cerca de 52 mil fam\u00edlias em Minas ainda podem receber desconto na conta de luz\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/tarifa-social-e-desconto-social-cerca-de-52-mil-familias-em-minas-ainda-podem-receber-desconto-na-conta-de-luz\/\" aria-label=\"Read more about Tarifa Social e Desconto Social: cerca de 52 mil fam\u00edlias em Minas ainda podem receber desconto na conta de luz\">Ler mais<\/a><\/p>\n","protected":false},"author":7,"featured_media":145202,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,2893,1,6,7660],"tags":[],"class_list":["post-145201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-muriae","category-cotidiano","category-gerais","category-regiao","category-slide-principal"],"acf":[],"aioseo_notices":[],"views":0,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/145201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=145201"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/145201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/145202"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=145201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=145201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=145201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}