{"id":145200,"date":"2026-05-13T09:59:04","date_gmt":"2026-05-13T12:59:04","guid":{"rendered":"https:\/\/anoticiaonline.com.br\/site\/?p=145200"},"modified":"2026-05-13T09:59:04","modified_gmt":"2026-05-13T12:59:04","slug":"coluna-esplanada-13-5-26","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/coluna-esplanada-13-5-26\/","title":{"rendered":"Coluna Esplanada 13\/5\/26"},"content":{"rendered":"<p><strong>Fio desencapado <\/strong><\/p>\n<p>O mercado de energia est\u00e1 intrigado com a decis\u00e3o Governo Federal de n\u00e3o incluir as concess\u00f5es da Enel no Rio de Janeiro e no Cear\u00e1 no pacote de renova\u00e7\u00f5es anunciados na semana passada. A Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) havia recomendado a renova\u00e7\u00e3o das concess\u00f5es da distribuidora nestes dois Estados \u2013 embora a ag\u00eancia tenha renovado antecipadamente 14 concess\u00f5es de distribui\u00e7\u00e3o. Rio e Cear\u00e1 apresentam n\u00fameros melhores que boa parte das concess\u00f5es renovadas, segundo analistas. Um exemplo \u00e9 a Light, que distribui energia para 31 munic\u00edpios do Rio de Janeiro, e est\u00e1 em recupera\u00e7\u00e3o judicial desde 2023. No Rio, o tempo m\u00e9dio de atendimento para religar a energia, no per\u00edodo de abril\/25 a mar\u00e7o\/26, foi de 419 minutos da Enel e de 534 minutos da Light. A m\u00e9dia nacional foi de 437 minutos. Da mesma forma, a Coelba, que atende regi\u00f5es da Bahia, registrou 639 minutos em m\u00e9dia para atendimento para religa\u00e7\u00e3o de energia, a pior m\u00e9dia nacional.<\/p>\n<p><strong>A voz de Zema<\/strong><\/p>\n<p>As cr\u00edticas do governador de Minas Gerais, Romeu Zema (Novo), com o Supremo Tribunal Federal, t\u00eam dado a ele notoriedade, que pode alavanc\u00e1-lo nas elei\u00e7\u00f5es deste ano. Embora repita que \u00e9 o candidato da 3\u00aa via, Zema surge a cada dia mais entre portas citado como o potencial vice de Fl\u00e1vio Bolsonaro (PL). O mineiro \u00e9 a voz para assuntos bombas que o presidenci\u00e1vel quer, mas n\u00e3o pode ecoar.<\/p>\n<p><strong>F\u00faria em Rond\u00f4nia<\/strong><\/p>\n<p>Instituto Novo Perfil Pesquisas: Para 74,4% dos eleitores de Rond\u00f4nia, a gest\u00e3o do Governo precisa de mudan\u00e7a, enquanto 25,6% defendem a continuidade. A avalia\u00e7\u00e3o da gest\u00e3o tamb\u00e9m aparece pressionada: 61% desaprovam a forma como o governador, Cel. Marcos Rocha, conduz a administra\u00e7\u00e3o \u2013 e 39% aprovam. O atual governador \u00e9 do PSD, cujo pr\u00e9-candidato ao Governo \u00e9 o ex-prefeito de Cacoal Adailton F\u00faria.<\/p>\n<p><strong>Golpes no <em>e-commerce<\/em><\/strong><\/p>\n<p>Golpistas miraram principalmente a gera\u00e7\u00e3o <em>millennials<\/em> nas tentativas de fraude no <em>e-commerce<\/em> em 2025. Foram 599,9 mil ocorr\u00eancias. A Gera\u00e7\u00e3o Z, com 505,5 mil dilig\u00eancias e a maior taxa proporcional de risco (2,2%), e a gera\u00e7\u00e3o X, com 297,1 mil, completam o top 3 no ranking de v\u00edtimas no ambiente digital. Os dados s\u00e3o de Estudo da Serasa Experian sobre transa\u00e7\u00f5es fraudulentas no varejo digital.<\/p>\n<p><strong>Balel\u00f4metro<\/strong><\/p>\n<p>Mais uma para o Balel\u00f4metro da <strong>Coluna<\/strong> \u2013 o espa\u00e7o que cita tudo o que foi combinado e nada resolvido, com vi\u00e9s eleitoreiro dos mandat\u00e1rios. O Desenrola Brasil, anunciado pelo Governo Federal para enfrentar o endividamento recorde no Pa\u00eds, avan\u00e7a apenas em plataformas digitais medianas que buscam a confian\u00e7a dos bancos, os reais credores, mas que desconfiam das plataformas&#8230; E segue o drama do brasileiro.<\/p>\n<p><strong>Brasil no Vaticano<\/strong><\/p>\n<p>Reitor da PUC-Rio, o padre Anderson Pedroso divide os holofotes com o cardeal portugu\u00eas Jos\u00e9 Tolentino de Mendon\u00e7a em semin\u00e1rio sobre Padre Ant\u00f4nio Vieira, em Roma. O encontro ocorre nas comemora\u00e7\u00f5es pelos 200 anos das rela\u00e7\u00f5es diplom\u00e1ticas entre Brasil e Santa S\u00e9, iniciadas oficialmente em 1826, quando o Papa Le\u00e3o XII recebeu as credenciais do 1\u00ba representante brasileiro no Vaticano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fio desencapado O mercado de energia est\u00e1 intrigado com a decis\u00e3o Governo Federal de n\u00e3o incluir as concess\u00f5es da Enel no Rio de Janeiro e no Cear\u00e1 no pacote de renova\u00e7\u00f5es anunciados na semana passada. A Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel) havia recomendado a renova\u00e7\u00e3o das concess\u00f5es da distribuidora nestes dois Estados \u2013 embora &#8230; <a title=\"Coluna Esplanada 13\/5\/26\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/coluna-esplanada-13-5-26\/\" aria-label=\"Read more about Coluna Esplanada 13\/5\/26\">Ler mais<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7690],"tags":[],"class_list":["post-145200","post","type-post","status-publish","format-standard","hentry","category-opiniao"],"acf":[],"aioseo_notices":[],"views":2,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/145200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=145200"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/145200\/revisions"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=145200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=145200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=145200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}