{"id":145144,"date":"2026-05-11T09:00:14","date_gmt":"2026-05-11T12:00:14","guid":{"rendered":"https:\/\/anoticiaonline.com.br\/site\/?p=145144"},"modified":"2026-05-11T09:00:14","modified_gmt":"2026-05-11T12:00:14","slug":"coluna-esplanada-11-5-26","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/coluna-esplanada-11-5-26\/","title":{"rendered":"Coluna Esplanada 11\/5\/26"},"content":{"rendered":"<p><strong>BB &#8211; <\/strong><\/p>\n<p>Enquanto os bancos privados anunciam o tradicional lucro l\u00edquido trimestral em bilh\u00f5es de reais, e a cada ano maiores, o desempenho do Banco do Brasil que ser\u00e1 divulgado nos pr\u00f3ximos dias ser\u00e1 \u201chorr\u00edvel\u201d \u2013 assim cravam analistas de mercado que j\u00e1 tiveram acesso ao balan\u00e7o da institui\u00e7\u00e3o de capital misto. O BB n\u00e3o alcan\u00e7ou os n\u00fameros dos anos anteriores para o per\u00edodo. E a dire\u00e7\u00e3o procura uma resposta plaus\u00edvel para n\u00e3o citar incompet\u00eancia. Por\u00e9m n\u00e3o tem op\u00e7\u00e3o no vocabul\u00e1rio, s\u00f3 vai disfar\u00e7ar.<\/p>\n<p><strong>Acabouuuu<\/strong><\/p>\n<p>O ano j\u00e1 acabou no Congresso Nacional. Boa parte dos deputados, em especial, e alguns senadores j\u00e1 ficam mais nos escrit\u00f3rios da base eleitoral. Muitos servidores pediram dispensa no Congresso para bater ponto nos redutos. Hugo Motta e Davi Alcolumbre est\u00e3o combinados de dar celeridade (e enterrar) a PEC do fim da jornada 6 x 1. Depois \u00e9 tchau, Bras\u00edlia, at\u00e9 as urnas!<\/p>\n<p><strong>Em \u201chome-office\u201d<\/strong><\/p>\n<p>O que se sabe em Salvador, a capital do mar, do ax\u00e9 e da alegria, \u00e9 que o procurador e advogado Eug\u00eanio Kruschewsky n\u00e3o curte nada nem tem sa\u00eddo de casa. \u00c9 para evitar olhares atravessados, vaias em restaurante e at\u00e9 cobran\u00e7as de populares sobre a sua rela\u00e7\u00e3o com o Daniel Vorcaro. Kruschewsky \u00e9 o homem que recebeu R$ 54 milh\u00f5es em honor\u00e1rios do \u201cbanqueiro\u201d, algo bem incompat\u00edvel para uma banca na pra\u00e7a por l\u00e1.<\/p>\n<p><strong>Maternidade &amp; carreira<\/strong><\/p>\n<p>Pesquisa Serasa Experian em suas redes sociais, com 327 participantes, revela que 58% das pessoas consideram a flexibilidade no trabalho, com jornada adapt\u00e1vel e <em>home office<\/em>, o principal fator para o crescimento profissional de m\u00e3es. Seguido por apoio da lideran\u00e7a (19%), cultura organizacional (14%), e benef\u00edcios como creche e aux\u00edlios (9%). Os dados fazem press\u00e3o para que empresas invistam nesses modelos flex\u00edveis.<\/p>\n<p><strong>Hantav\u00edrus<\/strong><\/p>\n<p>O hantav\u00edrus \u2013 doen\u00e7a transmitida por contato de humanos com secre\u00e7\u00f5es de roedores silvestres \u2013 preocupa turistas brasileiros que adoram um transatl\u00e2ntico. Um navio no mar da Europa ret\u00e9m 150 pessoas ap\u00f3s quatro mortes. Rosana Richtmann, m\u00e9dica do Lab. Exame, destaca que a contamina\u00e7\u00e3o acontece pela inala\u00e7\u00e3o de part\u00edculas das secre\u00e7\u00f5es e que a transmiss\u00e3o entre humanos \u00e9 poss\u00edvel, mas em situa\u00e7\u00f5es espec\u00edficas.<\/p>\n<p><strong>Al\u00f4, turma do TI<\/strong><\/p>\n<p>Voltado a startups SaaS, a 2\u00aa edi\u00e7\u00e3o do Programa Ideias Imply\u00ae foi lan\u00e7ada com investimentos que podem chegar a R$ 500 mil por projeto. Al\u00e9m de suporte t\u00e9cnico e acesso ao mercado, os participantes ter\u00e3o conex\u00e3o com a infraestrutura e ecossistema de inova\u00e7\u00e3o da empresa. As inscri\u00e7\u00f5es ficam abertas at\u00e9 29 de maio. O programa busca solu\u00e7\u00f5es em est\u00e1gio de MVP, em \u00e1reas como fintech, healthtech e IA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BB &#8211; Enquanto os bancos privados anunciam o tradicional lucro l\u00edquido trimestral em bilh\u00f5es de reais, e a cada ano maiores, o desempenho do Banco do Brasil que ser\u00e1 divulgado nos pr\u00f3ximos dias ser\u00e1 \u201chorr\u00edvel\u201d \u2013 assim cravam analistas de mercado que j\u00e1 tiveram acesso ao balan\u00e7o da institui\u00e7\u00e3o de capital misto. O BB n\u00e3o &#8230; <a title=\"Coluna Esplanada 11\/5\/26\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/coluna-esplanada-11-5-26\/\" aria-label=\"Read more about Coluna Esplanada 11\/5\/26\">Ler mais<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7690],"tags":[],"class_list":["post-145144","post","type-post","status-publish","format-standard","hentry","category-opiniao"],"acf":[],"aioseo_notices":[],"views":5,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/145144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=145144"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/145144\/revisions"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=145144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=145144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=145144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}