{"id":139874,"date":"2025-10-02T09:44:18","date_gmt":"2025-10-02T12:44:18","guid":{"rendered":"https:\/\/anoticiaonline.com.br\/site\/?p=139874"},"modified":"2025-10-02T09:44:37","modified_gmt":"2025-10-02T12:44:37","slug":"coluna-esplanada-2-10-25","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/coluna-esplanada-2-10-25\/","title":{"rendered":"Coluna Esplanada 2\/10\/25"},"content":{"rendered":"\n<p>O Sistema \u00danico de Sa\u00fade (SUS) registrou 3.892 atendimentos em casos de ludopatia (v\u00edcio em jogos) de 2022 a setembro de 2025, segundo informado \u00e0 Coluna pelo Minist\u00e9rio da Sa\u00fade (MS). S\u00e3o Paulo (1.828) e Rond\u00f4nia (1295) s\u00e3o os Estados que lideram as ocorr\u00eancias. Esses v\u00edcios t\u00eam aumentado consideravelmente ano a ano devido as casas de apostas online Os levantamentos s\u00e3o relatados ao MS pelos pr\u00f3prios Estados, mas nem todos os anos das unidades federativas foram catalogados. Al\u00e9m disso, h\u00e1 casos de ludopatia que podem ter sido classificados como ansiedade ou depress\u00e3o. Ou seja, o n\u00famero total pode ser ainda maior do que o informado. At\u00e9 setembro deste ano, foram notificados 407 casos, com os maiores n\u00fameros em S\u00e3o Paulo (141), Rond\u00f4nia (36) e Minas Gerais (22).<\/p>\n\n\n\n<p><strong>Justi\u00e7a tardia<\/strong><\/p>\n\n\n\n<p>A Justi\u00e7a Federal condenou a Ag\u00eancia Nacional de Transportes Terrestres (ANTT) a pagar uma indeniza\u00e7\u00e3o por danos morais e materiais no valor de R$ 30.862,00 a um funcion\u00e1rio que sofreu ass\u00e9dio por parte dos superiores. Um dos denunciados \u00e9 Felipe Ricardo Costa Freitas, ex-superintendente de Fiscaliza\u00e7\u00e3o da ANTT, que caiu do cargo em setembro de 2024 \u2013 o caso foi anunciado pela Coluna.<\/p>\n\n\n\n<p><strong>Um j\u00e1 foi<\/strong><\/p>\n\n\n\n<p>Ap\u00f3s press\u00e3o do Brasil, o M\u00e9xico, tamb\u00e9m sob o governo da esquerda, finalmente escolheu o novo Embaixador para Bras\u00edlia. Ser\u00e1 o diplomata Carlos Eugenio Garc\u00eda de Alba Zepeda, aceito prontamente pelo Itamaraty. Zepeda j\u00e1 atuou como Embaixador na It\u00e1lia e Irlanda, al\u00e9m de ter sido c\u00f4nsul em Los Angeles.<\/p>\n\n\n\n<p><strong>Est\u00e1 em todas<\/strong><\/p>\n\n\n\n<p>O ex-ministro Jos\u00e9 Dirceu voltou em alta e est\u00e1 marcando presen\u00e7a em eventos pelo Brasil. Dirceu \u00e9 um dos nomes confirmados para a 3\u00aa edi\u00e7\u00e3o do Pensar Brasil 2025!, que ter\u00e1 como tema o \u201cOr\u00e7amento e Desenvolvimento: Caminhos para a Justi\u00e7a Social\u201d. Al\u00e9m dele, est\u00e3o confirmados Vital do R\u00eago (Presidente do TCU), Ant\u00f4nio Anastasia (Ministro do TCU) e Bernard Appy (Economista e Secret\u00e1rio da Reforma Tribut\u00e1ria).<\/p>\n\n\n\n<p><strong>PCdoB e a China<\/strong><\/p>\n\n\n\n<p>Daniel Almeida Filho, secret\u00e1rio de Desenvolvimento Tecnol\u00f3gico e Inova\u00e7\u00e3o do MCTI e filho do deputado federal Daniel Almeida (PCdoB-BA), est\u00e1 na China representando o Brasil no 18\u00ba F\u00f3rum de Inova\u00e7\u00e3o de Pujiang 2025. O PCdoB, que controla o MCTI, \u00e9 o partido preferido dos chineses. Nas miss\u00f5es organizadas pela Embaixada, a prefer\u00eancia s\u00e3o os parlamentares do PCdoB.<\/p>\n\n\n\n<p><strong>Gravidez na adolesc\u00eancia<\/strong><\/p>\n\n\n\n<p>Um estudo da Federa\u00e7\u00e3o Brasileira das Associa\u00e7\u00f5es de Ginecologia e Obstetr\u00edcia mostra que antes da pandemia 55% das gesta\u00e7\u00f5es no Brasil n\u00e3o eram planejadas e ap\u00f3s a pandemia este n\u00famero subiu para 62%. Entre as adolescentes o \u00edndice \u00e9 ainda pior, e pode atingir os 80%. E apesar do dispositivo intrauterino (DIU) ser um dos mais eficazes, a ades\u00e3o \u00e9 apenas 4% entre as mulheres.<\/p>\n\n\n\n<p><strong>ESPLANADEIRA<\/strong><\/p>\n\n\n\n<p>#<strong>Papo de Acionista<\/strong> debate urg\u00eancia da ciberseguran\u00e7a para empresas, hoje. #<strong>Gilvan Bueno<\/strong> representa Brasil na Wall Street Lusophone Week em Nova Iorque. #<strong>Maple Bear<\/strong> realizou 4\u00aa Terry Fox Run em prol do INCAvolunt\u00e1rio no RJ. #Ex-Presidente <strong>Jos\u00e9 Sarney<\/strong> \u00e9 homenageado pelos 40 anos do Programa Calha Norte. #<strong>MedLevensohn<\/strong> apontou aumento de 294% na venda de testes r\u00e1pidos para Covid-19 em agosto. #<strong>Bureau Veritas<\/strong>, l\u00edder em TIC, lan\u00e7a certifica\u00e7\u00e3o de IA com foco em compliance e gest\u00e3o de riscos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Sistema \u00danico de Sa\u00fade (SUS) registrou 3.892 atendimentos em casos de ludopatia (v\u00edcio em jogos) de 2022 a setembro de 2025, segundo informado \u00e0 Coluna pelo Minist\u00e9rio da Sa\u00fade (MS). S\u00e3o Paulo (1.828) e Rond\u00f4nia (1295) s\u00e3o os Estados que lideram as ocorr\u00eancias. Esses v\u00edcios t\u00eam aumentado consideravelmente ano a ano devido as casas &#8230; <a title=\"Coluna Esplanada 2\/10\/25\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/coluna-esplanada-2-10-25\/\" aria-label=\"Read more about Coluna Esplanada 2\/10\/25\">Ler mais<\/a><\/p>\n","protected":false},"author":7,"featured_media":139875,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":true,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7690],"tags":[],"class_list":["post-139874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opiniao"],"acf":[],"aioseo_notices":[],"views":43,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/139874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=139874"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/139874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media\/139875"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=139874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=139874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=139874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}