{"id":128822,"date":"2024-09-05T08:27:58","date_gmt":"2024-09-05T11:27:58","guid":{"rendered":"http:\/\/anoticiaonline.com.br\/site\/?p=128822"},"modified":"2024-09-05T08:27:58","modified_gmt":"2024-09-05T11:27:58","slug":"coluna-esplanada-5-9-24","status":"publish","type":"post","link":"https:\/\/anoticiaonline.com.br\/site\/coluna-esplanada-5-9-24\/","title":{"rendered":"Coluna Esplanada 5\/9\/24"},"content":{"rendered":"\n<p>A ascens\u00e3o do nome do deputado federal Hugo Motta (Rep-PB) como o candidato de consenso do Pal\u00e1cio e de Arthur Lira \u00e0 Presid\u00eancia da C\u00e2mara para fevereiro trouxe o cachimbo da paz \u00e0s mesas e um problema futuro a resolver. Avalizado pelo presidente do Republicanos, deputado Marcos Pereira (SP) \u2013 que abriu m\u00e3o da disputa ap\u00f3s muita insist\u00eancia de aliados \u2013 Motta surge como o mais palat\u00e1vel ao Centr\u00e3o. \u201cN\u00e3o tenho d\u00favida de que todos estar\u00e3o ao lado dele; j\u00e1 que seu nome \u00e9 uma unanimidade\u201d, diz \u00e0 <strong>Coluna<\/strong> o deputado J\u00falio Lopes (PP-RJ). Aos 34 anos, Motta n\u00e3o \u00e9 um novato. Est\u00e1 no 4\u00ba mandato e circula bem entre as bancadas. O desafio a resolver \u00e9 o futuro Elmar Nascimento (Uni\u00e3o-BA), at\u00e9 ontem o nome de Lira para sua sucess\u00e3o. Os convescotes pr\u00e9-acordaram que o baiano ser\u00e1 indicado a uma vaga futura no TCU ano que vem.<\/p>\n\n\n\n<p><strong>Mais crimes<\/strong><\/p>\n\n\n\n<p>A Opera\u00e7\u00e3o Rei do Crime rendeu v\u00e1rias pris\u00f5es preventivas. A PF desmantelou complexa quadrilha que lavava dinheiro da fac\u00e7\u00e3o PCC em postos de gasolina. Mas a morte do principal delator derrubou todo o trabalho da pol\u00edcia. Agora, o grupo criminoso segue ainda mais forte: investe em grande terminal de armazenamento de combust\u00edveis na regi\u00e3o de Guarulhos (SP). O que mais chama aten\u00e7\u00e3o \u00e9 que eles est\u00e3o derrubando \u00e1rvores e desmatando terrenos sem nenhuma autoriza\u00e7\u00e3o de \u00f3rg\u00e3o ambiental. Todas as autoridades fingem que n\u00e3o v\u00eaem.<\/p>\n\n\n\n<p><strong>Hein!? Onde!?<\/strong><\/p>\n\n\n\n<p>Uruguai, Argentina, Costa Rica, Guatemala, Paraguai, Peru e Rep\u00fablica Dominicana firmaram declara\u00e7\u00e3o para repudiar \u201cde maneira inequ\u00edvoca e absoluta\u201d a ordem de pris\u00e3o contra o presidenci\u00e1vel Edmundo Gonz\u00e1lez na Venezuela. A diplomacia brasileira, sob o assessor presidencial Celso Amorim, prefere o sil\u00eancio.<\/p>\n\n\n\n<p><strong>Dois pesos<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"677\" src=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2024\/09\/5-09-24.jpg\" alt=\"\" class=\"wp-image-128825\" srcset=\"https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2024\/09\/5-09-24.jpg 700w, https:\/\/anoticiaonline.com.br\/site\/wp-content\/uploads\/2024\/09\/5-09-24-300x290.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/figure>\n\n\n\n<p>Enquanto o Comit\u00ea Ol\u00edmpico Brasileiro (sede Rio) pagou R$ 350 mil aos medalhistas de ouro, R$ 210 mil aos de prata e R$ 140 mil aos de bronze, Os paral\u00edmpicos v\u00e3o voltar de Paris com a premia\u00e7\u00e3o bem menor: R$ 250 mil para ouro, R$ 100 mil e R$ 50 mil, respectivamente. Apesar de o Comit\u00ea Paral\u00edmpico Brasileiro (SP) n\u00e3o ter liga\u00e7\u00e3o com o COB, vergonha para os patrocinadores a aus\u00eancia da equidade de premia\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>Adeus da mexicana<\/strong><\/p>\n\n\n\n<p>No dia 13, a escritora Laura Esquivel, embaixadora do M\u00e9xico no Brasil, se despedir\u00e1 de Bras\u00edlia, na festa pelos 190 anos das rela\u00e7\u00f5es diplom\u00e1ticas entre os dois pa\u00edses. Ela assumiu o cargo em julho de 2022 e adotou um perfil extremamente discreto. Esquivel, por\u00e9m, n\u00e3o conseguiu aproximar mais Brasil e M\u00e9xico, apesar da identidade ideol\u00f3gica entre Lula e L\u00f3pez Obrador. O Brasil n\u00e3o apoia o ingresso dos mexicanos no BRICS.<\/p>\n\n\n\n<p><strong>Poder &amp; Igreja<\/strong><\/p>\n\n\n\n<p>O senador Marcos Pontes (PL-SP) instalou ontem a Frente Parlamentar Cat\u00f3lica Apost\u00f3lica Romana, com a ades\u00e3o de 54 senadores e um deputado. O Arcebispo de Bras\u00edlia, Dom Paulo Cezar Costa, fez quest\u00e3o de comparecer. Ponte contou, ainda, com as presen\u00e7as de Benito Liao, diplomata da Embaixada de Taiwan que ajuda na reforma dos sinos da Catedral de Bras\u00edlia, e de um representante da Embaixada de Israel.<\/p>\n\n\n\n<p><strong>ESPLANADEIRA<\/strong><\/p>\n\n\n\n<p>#<strong>99Pay<\/strong> ultrapassa a marca de R$ 1,2 bi em empr\u00e9stimo pessoal. #<strong>Anac<\/strong> promove exibi\u00e7\u00f5es gratuitas do filme \u201cOnly Up\u201d. #<strong>Europa Purificadores<\/strong> leva \u00e1gua tratada \u00e0 comunidade quilombola no interior da Bahia. #<strong>Lalin Witch<\/strong> abre a exposi\u00e7\u00e3o &#8216;Obl\u00edvio&#8217;, na Galeria Dobra, na Bhering, RJ, dia 10. #<strong>Paula Klien<\/strong> autografa \u201cTodas as Minhas Mortes\u201d na Bienal do Livro de SP. #<strong>Rede Liberdade <\/strong>e<strong> ITS<\/strong> lan\u00e7am Vig\u00edlia para monitorar viol\u00eancia pol\u00edtica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ascens\u00e3o do nome do deputado federal Hugo Motta (Rep-PB) como o candidato de consenso do Pal\u00e1cio e de Arthur Lira \u00e0 Presid\u00eancia da C\u00e2mara para fevereiro trouxe o cachimbo da paz \u00e0s mesas e um problema futuro a resolver. Avalizado pelo presidente do Republicanos, deputado Marcos Pereira (SP) \u2013 que abriu m\u00e3o da disputa &#8230; <a title=\"Coluna Esplanada 5\/9\/24\" class=\"read-more\" href=\"https:\/\/anoticiaonline.com.br\/site\/coluna-esplanada-5-9-24\/\" aria-label=\"Read more about Coluna Esplanada 5\/9\/24\">Ler mais<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[30,2893,7690],"tags":[],"class_list":["post-128822","post","type-post","status-publish","format-standard","hentry","category-muriae","category-cotidiano","category-opiniao"],"acf":[],"aioseo_notices":[],"views":97,"_links":{"self":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/128822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/comments?post=128822"}],"version-history":[{"count":0,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/posts\/128822\/revisions"}],"wp:attachment":[{"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/media?parent=128822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/categories?post=128822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anoticiaonline.com.br\/site\/wp-json\/wp\/v2\/tags?post=128822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}